{"id":7505,"date":"2024-12-12T07:00:29","date_gmt":"2024-12-12T10:00:29","guid":{"rendered":"https:\/\/www.divvino.com.br\/blog\/?p=7505"},"modified":"2025-01-22T15:10:55","modified_gmt":"2025-01-22T18:10:55","slug":"drinks-com-prosecco","status":"publish","type":"post","link":"https:\/\/www.divvino.com.br\/blog\/drinks-com-prosecco\/","title":{"rendered":"16 drinks com espumante para se deliciar nos dias quentes"},"content":{"rendered":"<p><span data-contrast=\"none\">Se os dias quentes pedem por refresco, nada melhor do que celebrar esses momentos acompanhado de <\/span><span data-contrast=\"none\">drinks com espumante<\/span><span data-contrast=\"none\">. Leves e elegantes, a bebida proporciona sofistica\u00e7\u00e3o para roubar a cena em festas, celebra\u00e7\u00f5es, eventos ao ar livre ou para relaxar ao final do dia.<\/span><span data-ccp-props=\"{&quot;134245417&quot;:false}\">\u00a0<\/span><span data-ccp-props=\"{&quot;134245417&quot;:false}\">\u00a0<\/span><!--more--><\/p>\n<p><span data-contrast=\"none\">A seguir, vamos apresentar 16 receitas de <\/span><span data-contrast=\"none\">coquetel com espumante <\/span><span data-contrast=\"none\">perfeitas para essas ocasi\u00f5es. Prepare-se para descobrir combina\u00e7\u00f5es tradicionais, \u00fanicas e sabores surpreendentes que v\u00e3o deixar seus encontros inesquec\u00edveis. Pegue sua ta\u00e7a e venha explorar essas deliciosas op\u00e7\u00f5es!<\/span><span data-ccp-props=\"{&quot;134245417&quot;:false}\">\u00a0<\/span><\/p>\n<p><a href=\"https:\/\/clube.divvino.com.br\/?utm_source=blog&amp;utm_medium=post&amp;utm_content=clubed&amp;utm_campaign=drinks-com-espumante\"><span data-ccp-props=\"{&quot;134245417&quot;:false}\"> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-10021 size-full\" src=\"https:\/\/www.divvino.com.br\/blog\/wp-content\/uploads\/2023\/12\/banner-clubed-garanta-mais-descontos.png\" alt=\"banner clube D garanta mais descontos\" width=\"856\" height=\"121\" srcset=\"https:\/\/www.divvino.com.br\/blog\/wp-content\/uploads\/2023\/12\/banner-clubed-garanta-mais-descontos.png 856w, https:\/\/www.divvino.com.br\/blog\/wp-content\/uploads\/2023\/12\/banner-clubed-garanta-mais-descontos-300x42.png 300w, https:\/\/www.divvino.com.br\/blog\/wp-content\/uploads\/2023\/12\/banner-clubed-garanta-mais-descontos-768x109.png 768w\" sizes=\"(max-width: 856px) 100vw, 856px\" \/><\/span><\/a><\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_69_1 counter-hierarchy ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title \" >Conte&uacute;do do post<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #571b10;color:#571b10\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #571b10;color:#571b10\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.divvino.com.br\/blog\/drinks-com-prosecco\/#1_Bellini\" title=\"1. Bellini\">1. Bellini<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.divvino.com.br\/blog\/drinks-com-prosecco\/#Bellini\" title=\"Bellini\">Bellini<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.divvino.com.br\/blog\/drinks-com-prosecco\/#2_Rossini\" title=\"2. Rossini\">2. Rossini<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.divvino.com.br\/blog\/drinks-com-prosecco\/#Rossini\" title=\"Rossini\">Rossini<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/www.divvino.com.br\/blog\/drinks-com-prosecco\/#3_Aperol_Spritz\" title=\"3. Aperol Spritz\">3. Aperol Spritz<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/www.divvino.com.br\/blog\/drinks-com-prosecco\/#Aperol_Spritz\" title=\"Aperol Spritz\">Aperol Spritz<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/www.divvino.com.br\/blog\/drinks-com-prosecco\/#4_Limoncello_Spritz\" title=\"4. Limoncello Spritz\u00a0\">4. Limoncello Spritz\u00a0<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/www.divvino.com.br\/blog\/drinks-com-prosecco\/#Limoncello_Spritz\" title=\"Limoncello Spritz\">Limoncello Spritz<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/www.divvino.com.br\/blog\/drinks-com-prosecco\/#5_Kir_Royale\" title=\"5. Kir Royale\u00a0\">5. Kir Royale\u00a0<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/www.divvino.com.br\/blog\/drinks-com-prosecco\/#Kir_Royale\" title=\"Kir Royale\">Kir Royale<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/www.divvino.com.br\/blog\/drinks-com-prosecco\/#6_Negroni_Sbagliato\" title=\"6. Negroni Sbagliato\u00a0\">6. Negroni Sbagliato\u00a0<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/www.divvino.com.br\/blog\/drinks-com-prosecco\/#Negroni_Sbagliato\" title=\"Negroni Sbagliato\">Negroni Sbagliato<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/www.divvino.com.br\/blog\/drinks-com-prosecco\/#7_French_75\" title=\"7. French 75\u00a0\u00a0\">7. French 75\u00a0\u00a0<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-14\" href=\"https:\/\/www.divvino.com.br\/blog\/drinks-com-prosecco\/#French_75\" title=\"French 75\">French 75<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-15\" href=\"https:\/\/www.divvino.com.br\/blog\/drinks-com-prosecco\/#8_Death_in_Venice\" title=\"8. Death in Venice\u00a0\u00a0\">8. Death in Venice\u00a0\u00a0<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-16\" href=\"https:\/\/www.divvino.com.br\/blog\/drinks-com-prosecco\/#Death_in_Venice\" title=\"Death in Venice\">Death in Venice<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-17\" href=\"https:\/\/www.divvino.com.br\/blog\/drinks-com-prosecco\/#9_Champagne_cocktail\" title=\"9. Champagne cocktail\u00a0\u00a0\">9. Champagne cocktail\u00a0\u00a0<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-18\" href=\"https:\/\/www.divvino.com.br\/blog\/drinks-com-prosecco\/#Champagne_cocktail\" title=\"Champagne cocktail\">Champagne cocktail<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-19\" href=\"https:\/\/www.divvino.com.br\/blog\/drinks-com-prosecco\/#10_Pink_Elephant\" title=\"10. Pink Elephant\u00a0\u00a0\">10. Pink Elephant\u00a0\u00a0<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-20\" href=\"https:\/\/www.divvino.com.br\/blog\/drinks-com-prosecco\/#Pink_Elephant\" title=\"Pink Elephant\">Pink Elephant<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-21\" href=\"https:\/\/www.divvino.com.br\/blog\/drinks-com-prosecco\/#11_Sangria_com_espumante\" title=\"11. Sangria com espumante\u00a0\u00a0\">11. Sangria com espumante\u00a0\u00a0<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-22\" href=\"https:\/\/www.divvino.com.br\/blog\/drinks-com-prosecco\/#Sangria_com_espumante\" title=\"Sangria com espumante\">Sangria com espumante<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-23\" href=\"https:\/\/www.divvino.com.br\/blog\/drinks-com-prosecco\/#12_Clericot_tradicional\" title=\"12. Clericot tradicional\u00a0\u00a0\u00a0\">12. Clericot tradicional\u00a0\u00a0\u00a0<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-24\" href=\"https:\/\/www.divvino.com.br\/blog\/drinks-com-prosecco\/#Clericot_tradicional\" title=\"Clericot tradicional\">Clericot tradicional<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-25\" href=\"https:\/\/www.divvino.com.br\/blog\/drinks-com-prosecco\/#13_Hibisco_Spritz\" title=\"13. Hibisco Spritz\u00a0\u00a0\">13. Hibisco Spritz\u00a0\u00a0<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-26\" href=\"https:\/\/www.divvino.com.br\/blog\/drinks-com-prosecco\/#Hibisco_Spritz\" title=\"Hibisco Spritz\">Hibisco Spritz<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-27\" href=\"https:\/\/www.divvino.com.br\/blog\/drinks-com-prosecco\/#14_Batidinha_de_espumante_rose\" title=\"14. Batidinha de espumante ros\u00e9\u00a0\">14. Batidinha de espumante ros\u00e9\u00a0<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-28\" href=\"https:\/\/www.divvino.com.br\/blog\/drinks-com-prosecco\/#Batidinha_de_espumante_rose\" title=\"Batidinha de espumante ros\u00e9\">Batidinha de espumante ros\u00e9<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-29\" href=\"https:\/\/www.divvino.com.br\/blog\/drinks-com-prosecco\/#15_Sparkling_Sunrise\" title=\"15. Sparkling Sunrise\u00a0\u00a0\">15. Sparkling Sunrise\u00a0\u00a0<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-30\" href=\"https:\/\/www.divvino.com.br\/blog\/drinks-com-prosecco\/#Sparkling_Sunrise\" title=\"Sparkling Sunrise\">Sparkling Sunrise<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-31\" href=\"https:\/\/www.divvino.com.br\/blog\/drinks-com-prosecco\/#Poinsettia\" title=\"Poinsettia\">Poinsettia<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"1_Bellini\"><\/span><b>1. Bellini<\/b><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span class=\"TextRun SCXW67409192 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW67409192 BCX0\">Bellini \u00e9 o cl\u00e1ssico dos cl\u00e1ssicos, um dos mais famosos <\/span><\/span><span class=\"TextRun SCXW67409192 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW67409192 BCX0\">drinks com espumante<\/span><\/span><span class=\"TextRun SCXW67409192 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW67409192 BCX0\">. <\/span><\/span><span class=\"TextRun SCXW67409192 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW67409192 BCX0\">Criado em 1948, na It\u00e1lia, \u00e9 um coquetel ic\u00f4nico, saboroso e <\/span><span class=\"NormalTextRun SCXW67409192 BCX0\">super<\/span> <span class=\"NormalTextRun SCXW67409192 BCX0\">f\u00e1cil<\/span><span class=\"NormalTextRun SCXW67409192 BCX0\"> de preparar.<\/span> <\/span><span class=\"TextRun SCXW67409192 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW67409192 BCX0\">S<\/span><span class=\"NormalTextRun SCXW67409192 BCX0\">ua vers\u00e3o tradicional \u00e9 acompanhada do <\/span><\/span><a class=\"Hyperlink SCXW67409192 BCX0\" href=\"https:\/\/www.divvino.com.br\/blog\/prosecco-o-que-e\/\" target=\"_blank\" rel=\"noreferrer noopener\"><span class=\"TextRun Underlined SCXW67409192 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW67409192 BCX0\" data-ccp-charstyle=\"Hyperlink\">prosecco<\/span><\/span><\/a><span class=\"TextRun SCXW67409192 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW67409192 BCX0\">, <\/span><span class=\"NormalTextRun SCXW67409192 BCX0\">um tipo de <\/span><\/span><a class=\"Hyperlink SCXW67409192 BCX0\" href=\"https:\/\/www.divvino.com.br\/vinhos\/espumante\/?utm_source=blog&amp;utm_medium=post&amp;utm_content=espumante&amp;utm_campaign=drinks-com-espumante\" target=\"_blank\" rel=\"noreferrer noopener\"><span class=\"TextRun Underlined SCXW67409192 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW67409192 BCX0\" data-ccp-charstyle=\"Hyperlink\">espumante<\/span><\/span><\/a><span class=\"TextRun SCXW67409192 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW67409192 BCX0\"> elaborado nas regi\u00f5es de <\/span><\/span><a class=\"Hyperlink SCXW67409192 BCX0\" href=\"https:\/\/www.divvino.com.br\/blog\/regioes-vinicolas-da-italia\/\" target=\"_blank\" rel=\"noreferrer noopener\"><span class=\"TextRun Underlined SCXW67409192 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW67409192 BCX0\" data-ccp-charstyle=\"Hyperlink\">V\u00eaneto e <\/span><span class=\"NormalTextRun SCXW67409192 BCX0\" data-ccp-charstyle=\"Hyperlink\">Friuli<\/span><span class=\"NormalTextRun SCXW67409192 BCX0\" data-ccp-charstyle=\"Hyperlink\">-Venezia Giulia<\/span><\/span><\/a><span class=\"TextRun SCXW67409192 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW67409192 BCX0\">.<\/span><\/span><span class=\"EOP SCXW67409192 BCX0\" data-ccp-props=\"{&quot;134245417&quot;:false}\">\u00a0<\/span><\/p>\n<div id=\"recipe\"><\/div><div id=\"wprm-recipe-container-10025\" class=\"wprm-recipe-container\" data-recipe-id=\"10025\" data-servings=\"0\"><div class=\"wprm-recipe wprm-recipe-template-classic\"><div class=\"wprm-container-float-right\">\n\t<div class=\"wprm-recipe-image wprm-block-image-normal\"><img loading=\"lazy\" decoding=\"async\" style=\"border-width: 0px;border-style: solid;border-color: #666666;\" width=\"150\" height=\"150\" src=\"https:\/\/www.divvino.com.br\/blog\/wp-content\/uploads\/2023\/09\/drinks-com-prosecco-bellini-150x150.jpg\" class=\"attachment-150x150 size-150x150\" alt=\"drinks com Prosecco\" \/><\/div>\n\t<div class=\"wprm-spacer\" style=\"height: 5px\"><\/div>\n\t\n\t<div class=\"wprm-spacer\" style=\"height: 2px\"><\/div>\n\t<a href=\"https:\/\/www.divvino.com.br\/blog\/wprm_print\/bellini\" style=\"color: #333333;\" class=\"wprm-recipe-print wprm-recipe-link wprm-print-recipe-shortcode wprm-block-text-normal\" data-recipe-id=\"10025\" data-template=\"\" target=\"_blank\" rel=\"nofollow\"><span class=\"wprm-recipe-icon wprm-recipe-print-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"16px\" height=\"16px\" viewBox=\"0 0 24 24\"><g ><path fill=\"#333333\" d=\"M19,5.09V1c0-0.552-0.448-1-1-1H6C5.448,0,5,0.448,5,1v4.09C2.167,5.569,0,8.033,0,11v7c0,0.552,0.448,1,1,1h4v4c0,0.552,0.448,1,1,1h12c0.552,0,1-0.448,1-1v-4h4c0.552,0,1-0.448,1-1v-7C24,8.033,21.833,5.569,19,5.09z M7,2h10v3H7V2z M17,22H7v-9h10V22z M18,10c-0.552,0-1-0.448-1-1c0-0.552,0.448-1,1-1s1,0.448,1,1C19,9.552,18.552,10,18,10z\"\/><\/g><\/svg><\/span> Print<\/a>\n\t<a href=\"https:\/\/www.pinterest.com\/pin\/create\/bookmarklet\/?url=https%3A%2F%2Fwww.divvino.com.br%2Fblog%2Fdrinks-com-prosecco%2F&amp;media=https%3A%2F%2Fwww.divvino.com.br%2Fblog%2Fwp-content%2Fuploads%2F2023%2F09%2Fdrinks-com-prosecco-bellini.jpg&amp;description=Bellini&amp;is_video=false\" style=\"color: #333333;\" class=\"wprm-recipe-pin wprm-recipe-link wprm-block-text-normal\" target=\"_blank\" rel=\"nofollow noopener\" data-recipe=\"10025\" data-url=\"https:\/\/www.divvino.com.br\/blog\/drinks-com-prosecco\/\" data-media=\"https:\/\/www.divvino.com.br\/blog\/wp-content\/uploads\/2023\/09\/drinks-com-prosecco-bellini.jpg\" data-description=\"Bellini\" data-repin=\"\"><span class=\"wprm-recipe-icon wprm-recipe-pin-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" viewBox=\"0 0 24 24\"><g class=\"nc-icon-wrapper\" fill=\"#333333\"><path fill=\"#333333\" d=\"M12,0C5.4,0,0,5.4,0,12c0,5.1,3.2,9.4,7.6,11.2c-0.1-0.9-0.2-2.4,0-3.4c0.2-0.9,1.4-6,1.4-6S8.7,13,8.7,12 c0-1.7,1-2.9,2.2-2.9c1,0,1.5,0.8,1.5,1.7c0,1-0.7,2.6-1,4c-0.3,1.2,0.6,2.2,1.8,2.2c2.1,0,3.8-2.2,3.8-5.5c0-2.9-2.1-4.9-5-4.9 c-3.4,0-5.4,2.6-5.4,5.2c0,1,0.4,2.1,0.9,2.7c0.1,0.1,0.1,0.2,0.1,0.3c-0.1,0.4-0.3,1.2-0.3,1.4c-0.1,0.2-0.2,0.3-0.4,0.2 c-1.5-0.7-2.4-2.9-2.4-4.6c0-3.8,2.8-7.3,7.9-7.3c4.2,0,7.4,3,7.4,6.9c0,4.1-2.6,7.5-6.2,7.5c-1.2,0-2.4-0.6-2.8-1.4 c0,0-0.6,2.3-0.7,2.9c-0.3,1-1,2.3-1.5,3.1C9.6,23.8,10.8,24,12,24c6.6,0,12-5.4,12-12C24,5.4,18.6,0,12,0z\"><\/path><\/g><\/svg><\/span> Pin<\/a>\n\t\n<\/div>\n<h2 class=\"wprm-recipe-name wprm-block-text-bold\"><span class=\"ez-toc-section\" id=\"Bellini\"><\/span>Bellini<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<div class=\"wprm-spacer\" style=\"height: 5px\"><\/div>\n<div class=\"wprm-recipe-summary wprm-block-text-normal\">O Bellini \u00e9 um cl\u00e1ssico dos drinks com espumante. Delicioso e f\u00e1cil de fazer, \u00e9 um coquetel excelente para se refrescar!<\/div>\n<div class=\"wprm-spacer\"><\/div>\n\n<div class=\"wprm-spacer\"><\/div>\n\n<div class=\"wprm-spacer\"><\/div>\n\n\n\n\n\n<div class=\"wprm-recipe-ingredients-container wprm-recipe-10025-ingredients-container wprm-block-text-normal wprm-ingredient-style-regular wprm-recipe-images-before\" data-recipe=\"10025\" data-servings=\"0\"><h3 class=\"wprm-recipe-header wprm-recipe-ingredients-header wprm-block-text-bold wprm-align-left wprm-header-decoration-none\" style=\"\">Ingredients<\/h3><div class=\"wprm-recipe-ingredient-group\"><ul class=\"wprm-recipe-ingredients\"><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"0\"><span class=\"wprm-recipe-ingredient-amount\">50<\/span>&#32;<span class=\"wprm-recipe-ingredient-unit\">ml<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">de pur\u00ea ou suco de p\u00eassego<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"1\"><span class=\"wprm-recipe-ingredient-amount\">100<\/span>&#32;<span class=\"wprm-recipe-ingredient-unit\">ml<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">de prosecco gelado<\/span><\/li><\/ul><\/div><\/div>\n<div class=\"wprm-recipe-instructions-container wprm-recipe-10025-instructions-container wprm-block-text-normal\" data-recipe=\"10025\"><h3 class=\"wprm-recipe-header wprm-recipe-instructions-header wprm-block-text-bold wprm-align-left wprm-header-decoration-none\" style=\"\">Instructions<\/h3><div class=\"wprm-recipe-instruction-group\"><ul class=\"wprm-recipe-instructions\"><li id=\"wprm-recipe-10025-step-0-0\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\">Em uma ta\u00e7a fl\u00fbte gelada, adicione o pur\u00ea ou o suco de p\u00eassego.<\/div><\/li><li id=\"wprm-recipe-10025-step-0-1\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\">Depois, complete com Prosecco gelado.<\/div><\/li><li id=\"wprm-recipe-10025-step-0-2\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\">Mexa delicadamente e sirva em seguida.<\/div><\/li><\/ul><\/div><\/div>\n\n<div class=\"wprm-recipe-notes-container wprm-block-text-normal\"><h3 class=\"wprm-recipe-header wprm-recipe-notes-header wprm-block-text-bold wprm-align-left wprm-header-decoration-none\" style=\"\">Notes<\/h3><div class=\"wprm-recipe-notes\"><span style=\"display: block;\">Dica: para obter o pur\u00ea, passe uma lata de p\u00eassegos em calda em uma peneira para retirar o l\u00edquido. Depois, bata no liquidificador. <\/span><\/div><\/div>\n<\/div><\/div>\n<h2><span class=\"ez-toc-section\" id=\"2_Rossini\"><\/span><b>2. Rossini<\/b><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span class=\"TextRun SCXW12003513 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW12003513 BCX0\">O Rossini tamb\u00e9m \u00e9 um coquetel italiano, concebido em 1948 pelo mesmo criador do Bellini, Giuseppe Cipriani. Nesta vers\u00e3o<\/span><span class=\"NormalTextRun SCXW12003513 BCX0\"> da <\/span><\/span><span class=\"TextRun SCXW12003513 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW12003513 BCX0\">bebida com espumante<\/span><\/span><span class=\"TextRun SCXW12003513 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW12003513 BCX0\">, o <\/span><span class=\"NormalTextRun SpellingErrorV2Themed SCXW12003513 BCX0\">p<\/span><span class=\"NormalTextRun SpellingErrorV2Themed SCXW12003513 BCX0\">rosecco<\/span><span class=\"NormalTextRun SCXW12003513 BCX0\"> \u00e9 misturado ao pur\u00ea ou suco de morango.<\/span><\/span><span class=\"TextRun SCXW12003513 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW12003513 BCX0\"> Confira o modo de preparo!<\/span><\/span><span class=\"EOP SCXW12003513 BCX0\" data-ccp-props=\"{&quot;134245417&quot;:false}\">\u00a0<\/span><\/p>\n<div id=\"wprm-recipe-container-10042\" class=\"wprm-recipe-container\" data-recipe-id=\"10042\" data-servings=\"0\"><div class=\"wprm-recipe wprm-recipe-template-classic\"><div class=\"wprm-container-float-right\">\n\t<div class=\"wprm-recipe-image wprm-block-image-normal\"><img loading=\"lazy\" decoding=\"async\" style=\"border-width: 0px;border-style: solid;border-color: #666666;\" width=\"150\" height=\"150\" src=\"https:\/\/www.divvino.com.br\/blog\/wp-content\/uploads\/2023\/10\/rossini-150x150.jpg\" class=\"attachment-150x150 size-150x150\" alt=\"rossini\" srcset=\"https:\/\/www.divvino.com.br\/blog\/wp-content\/uploads\/2023\/10\/rossini-150x150.jpg 150w, https:\/\/www.divvino.com.br\/blog\/wp-content\/uploads\/2023\/10\/rossini-300x300.jpg 300w, https:\/\/www.divvino.com.br\/blog\/wp-content\/uploads\/2023\/10\/rossini.jpg 500w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/div>\n\t<div class=\"wprm-spacer\" style=\"height: 5px\"><\/div>\n\t\n\t<div class=\"wprm-spacer\" style=\"height: 2px\"><\/div>\n\t<a href=\"https:\/\/www.divvino.com.br\/blog\/wprm_print\/rossini\" style=\"color: #333333;\" class=\"wprm-recipe-print wprm-recipe-link wprm-print-recipe-shortcode wprm-block-text-normal\" data-recipe-id=\"10042\" data-template=\"\" target=\"_blank\" rel=\"nofollow\"><span class=\"wprm-recipe-icon wprm-recipe-print-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"16px\" height=\"16px\" viewBox=\"0 0 24 24\"><g ><path fill=\"#333333\" d=\"M19,5.09V1c0-0.552-0.448-1-1-1H6C5.448,0,5,0.448,5,1v4.09C2.167,5.569,0,8.033,0,11v7c0,0.552,0.448,1,1,1h4v4c0,0.552,0.448,1,1,1h12c0.552,0,1-0.448,1-1v-4h4c0.552,0,1-0.448,1-1v-7C24,8.033,21.833,5.569,19,5.09z M7,2h10v3H7V2z M17,22H7v-9h10V22z M18,10c-0.552,0-1-0.448-1-1c0-0.552,0.448-1,1-1s1,0.448,1,1C19,9.552,18.552,10,18,10z\"\/><\/g><\/svg><\/span> Print<\/a>\n\t<a href=\"https:\/\/www.pinterest.com\/pin\/create\/bookmarklet\/?url=https%3A%2F%2Fwww.divvino.com.br%2Fblog%2Fdrinks-com-prosecco%2F&amp;media=https%3A%2F%2Fwww.divvino.com.br%2Fblog%2Fwp-content%2Fuploads%2F2023%2F10%2Frossini.jpg&amp;description=Rossini&amp;is_video=false\" style=\"color: #333333;\" class=\"wprm-recipe-pin wprm-recipe-link wprm-block-text-normal\" target=\"_blank\" rel=\"nofollow noopener\" data-recipe=\"10042\" data-url=\"https:\/\/www.divvino.com.br\/blog\/drinks-com-prosecco\/\" data-media=\"https:\/\/www.divvino.com.br\/blog\/wp-content\/uploads\/2023\/10\/rossini.jpg\" data-description=\"Rossini\" data-repin=\"\"><span class=\"wprm-recipe-icon wprm-recipe-pin-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" viewBox=\"0 0 24 24\"><g class=\"nc-icon-wrapper\" fill=\"#333333\"><path fill=\"#333333\" d=\"M12,0C5.4,0,0,5.4,0,12c0,5.1,3.2,9.4,7.6,11.2c-0.1-0.9-0.2-2.4,0-3.4c0.2-0.9,1.4-6,1.4-6S8.7,13,8.7,12 c0-1.7,1-2.9,2.2-2.9c1,0,1.5,0.8,1.5,1.7c0,1-0.7,2.6-1,4c-0.3,1.2,0.6,2.2,1.8,2.2c2.1,0,3.8-2.2,3.8-5.5c0-2.9-2.1-4.9-5-4.9 c-3.4,0-5.4,2.6-5.4,5.2c0,1,0.4,2.1,0.9,2.7c0.1,0.1,0.1,0.2,0.1,0.3c-0.1,0.4-0.3,1.2-0.3,1.4c-0.1,0.2-0.2,0.3-0.4,0.2 c-1.5-0.7-2.4-2.9-2.4-4.6c0-3.8,2.8-7.3,7.9-7.3c4.2,0,7.4,3,7.4,6.9c0,4.1-2.6,7.5-6.2,7.5c-1.2,0-2.4-0.6-2.8-1.4 c0,0-0.6,2.3-0.7,2.9c-0.3,1-1,2.3-1.5,3.1C9.6,23.8,10.8,24,12,24c6.6,0,12-5.4,12-12C24,5.4,18.6,0,12,0z\"><\/path><\/g><\/svg><\/span> Pin<\/a>\n\t\n<\/div>\n<h2 class=\"wprm-recipe-name wprm-block-text-bold\"><span class=\"ez-toc-section\" id=\"Rossini\"><\/span>Rossini<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<div class=\"wprm-spacer\" style=\"height: 5px\"><\/div>\n<div class=\"wprm-recipe-summary wprm-block-text-normal\">Rossini \u00e9 uma vers\u00e3o do Bellini que substitui o p\u00eassego por morango. J\u00e1 experimentou? Veja o passo a passo para faz\u00ea-lo!<\/div>\n<div class=\"wprm-spacer\"><\/div>\n\n<div class=\"wprm-spacer\"><\/div>\n\n<div class=\"wprm-spacer\"><\/div>\n\n\n\n\n\n<div class=\"wprm-recipe-ingredients-container wprm-recipe-10042-ingredients-container wprm-block-text-normal wprm-ingredient-style-regular wprm-recipe-images-before\" data-recipe=\"10042\" data-servings=\"0\"><h3 class=\"wprm-recipe-header wprm-recipe-ingredients-header wprm-block-text-bold wprm-align-left wprm-header-decoration-none\" style=\"\">Ingredients<\/h3><div class=\"wprm-recipe-ingredient-group\"><ul class=\"wprm-recipe-ingredients\"><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"0\"><span class=\"wprm-recipe-ingredient-amount\">50<\/span>&#32;<span class=\"wprm-recipe-ingredient-unit\">ml<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">de pur\u00ea ou suco de morango<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"1\"><span class=\"wprm-recipe-ingredient-amount\">100<\/span>&#32;<span class=\"wprm-recipe-ingredient-unit\">ml<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">de prosecco gelado<\/span><\/li><\/ul><\/div><\/div>\n<div class=\"wprm-recipe-instructions-container wprm-recipe-10042-instructions-container wprm-block-text-normal\" data-recipe=\"10042\"><h3 class=\"wprm-recipe-header wprm-recipe-instructions-header wprm-block-text-bold wprm-align-left wprm-header-decoration-none\" style=\"\">Instructions<\/h3><div class=\"wprm-recipe-instruction-group\"><ul class=\"wprm-recipe-instructions\"><li id=\"wprm-recipe-10042-step-0-0\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\">Em uma ta\u00e7a fl\u00fbte ou vintage gelada, comece adicionando o pur\u00ea ou o suco da fruta.<\/div><\/li><li id=\"wprm-recipe-10042-step-0-1\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\">Em seguida, acrescente o prosecco.<\/div><\/li><li id=\"wprm-recipe-10042-step-0-2\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\">Misture delicadamente e seu drink com espumante e morango estar\u00e1 pronto!<\/div><\/li><\/ul><\/div><\/div>\n\n\n<\/div><\/div>\n<h2><span class=\"ez-toc-section\" id=\"3_Aperol_Spritz\"><\/span><b>3. <\/b><b>Aperol Spritz<\/b><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span class=\"TextRun SCXW75937157 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW75937157 BCX0\">Mais um cl\u00e1ssico italiano! O <\/span><\/span><a class=\"Hyperlink SCXW75937157 BCX0\" href=\"https:\/\/www.divvino.com.br\/kit-aperol-spritz-prod5390027\/p?utm_source=blog&amp;utm_medium=post&amp;utm_content=kit-aperol-spritz&amp;utm_campaign=drinks-com-espumante\" target=\"_blank\" rel=\"noreferrer noopener\"><span class=\"TextRun Underlined SCXW75937157 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW75937157 BCX0\" data-ccp-charstyle=\"Hyperlink\">Aperol<\/span> <span class=\"NormalTextRun SCXW75937157 BCX0\" data-ccp-charstyle=\"Hyperlink\">Spritz<\/span><\/span><\/a><span class=\"TextRun SCXW75937157 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"auto\"> <span class=\"NormalTextRun SCXW75937157 BCX0\">\u00e9 um <\/span><\/span><span class=\"TextRun SCXW75937157 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW75937157 BCX0\">drink com <\/span><\/span><a class=\"Hyperlink SCXW75937157 BCX0\" href=\"https:\/\/www.divvino.com.br\/aperitivo-aperol-750ml-3706113\/p\/?utm_source=blog&amp;utm_medium=post&amp;utm_content=aperol&amp;utm_campaign=drinks-com-espumante\" target=\"_blank\" rel=\"noreferrer noopener\"><span class=\"TextRun Underlined SCXW75937157 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW75937157 BCX0\" data-ccp-charstyle=\"Hyperlink\">Aperol<\/span><\/span><\/a><span class=\"TextRun SCXW75937157 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW75937157 BCX0\"> e espumante<\/span><\/span><span class=\"TextRun SCXW75937157 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW75937157 BCX0\">. F<\/span><span class=\"NormalTextRun SCXW75937157 BCX0\">oi criado em P\u00e1dua, na regi\u00e3o de <\/span><span class=\"NormalTextRun SCXW75937157 BCX0\">V\u00eaneto, na<\/span><span class=\"NormalTextRun SCXW75937157 BCX0\"> It\u00e1lia, pelos irm\u00e3os Silvio e Luigi Barbieri. Leva <\/span><span class=\"NormalTextRun SCXW75937157 BCX0\">o<\/span> <\/span><a class=\"Hyperlink SCXW75937157 BCX0\" href=\"https:\/\/www.divvino.com.br\/aperitivo-campari-bitter-748ml-5207810\/p\/?utm_source=blog&amp;utm_medium=post&amp;utm_content=campari&amp;utm_campaign=drinks-com-espumante\" target=\"_blank\" rel=\"noreferrer noopener\"><span class=\"TextRun Underlined SCXW75937157 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW75937157 BCX0\" data-ccp-charstyle=\"Hyperlink\">aperitivo<\/span><\/span><\/a><span class=\"TextRun SCXW75937157 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW75937157 BCX0\"> feito \u00e0 base de laranja e desenvolvido na mesma cidade que o coquetel, al\u00e9m de <\/span><span class=\"NormalTextRun SpellingErrorV2Themed SCXW75937157 BCX0\">p<\/span><span class=\"NormalTextRun SpellingErrorV2Themed SCXW75937157 BCX0\">rosecco<\/span><span class=\"NormalTextRun SCXW75937157 BCX0\">, \u00e1gua com g\u00e1s e laranja.<\/span> <\/span><span class=\"TextRun SCXW75937157 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW75937157 BCX0\">Veja como preparar!<\/span><\/span><span class=\"EOP SCXW75937157 BCX0\" data-ccp-props=\"{&quot;134245417&quot;:false}\">\u00a0<\/span><\/p>\n<div id=\"wprm-recipe-container-10027\" class=\"wprm-recipe-container\" data-recipe-id=\"10027\" data-servings=\"0\"><div class=\"wprm-recipe wprm-recipe-template-classic\"><div class=\"wprm-container-float-right\">\n\t<div class=\"wprm-recipe-image wprm-block-image-normal\"><img loading=\"lazy\" decoding=\"async\" style=\"border-width: 0px;border-style: solid;border-color: #666666;\" width=\"150\" height=\"150\" src=\"https:\/\/www.divvino.com.br\/blog\/wp-content\/uploads\/2023\/09\/drinks-com-prosecco-aperol-spritz-150x150.jpg\" class=\"attachment-150x150 size-150x150\" alt=\"duas pessoas bridando com Aperol Spritz, um drink com Prosecco\" \/><\/div>\n\t<div class=\"wprm-spacer\" style=\"height: 5px\"><\/div>\n\t\n\t<div class=\"wprm-spacer\" style=\"height: 2px\"><\/div>\n\t<a href=\"https:\/\/www.divvino.com.br\/blog\/wprm_print\/aperol-spritz\" style=\"color: #333333;\" class=\"wprm-recipe-print wprm-recipe-link wprm-print-recipe-shortcode wprm-block-text-normal\" data-recipe-id=\"10027\" data-template=\"\" target=\"_blank\" rel=\"nofollow\"><span class=\"wprm-recipe-icon wprm-recipe-print-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"16px\" height=\"16px\" viewBox=\"0 0 24 24\"><g ><path fill=\"#333333\" d=\"M19,5.09V1c0-0.552-0.448-1-1-1H6C5.448,0,5,0.448,5,1v4.09C2.167,5.569,0,8.033,0,11v7c0,0.552,0.448,1,1,1h4v4c0,0.552,0.448,1,1,1h12c0.552,0,1-0.448,1-1v-4h4c0.552,0,1-0.448,1-1v-7C24,8.033,21.833,5.569,19,5.09z M7,2h10v3H7V2z M17,22H7v-9h10V22z M18,10c-0.552,0-1-0.448-1-1c0-0.552,0.448-1,1-1s1,0.448,1,1C19,9.552,18.552,10,18,10z\"\/><\/g><\/svg><\/span> Print<\/a>\n\t<a href=\"https:\/\/www.pinterest.com\/pin\/create\/bookmarklet\/?url=https%3A%2F%2Fwww.divvino.com.br%2Fblog%2Fdrinks-com-prosecco%2F&amp;media=https%3A%2F%2Fwww.divvino.com.br%2Fblog%2Fwp-content%2Fuploads%2F2023%2F09%2Fdrinks-com-prosecco-aperol-spritz.jpg&amp;description=Aperol+Spritz&amp;is_video=false\" style=\"color: #333333;\" class=\"wprm-recipe-pin wprm-recipe-link wprm-block-text-normal\" target=\"_blank\" rel=\"nofollow noopener\" data-recipe=\"10027\" data-url=\"https:\/\/www.divvino.com.br\/blog\/drinks-com-prosecco\/\" data-media=\"https:\/\/www.divvino.com.br\/blog\/wp-content\/uploads\/2023\/09\/drinks-com-prosecco-aperol-spritz.jpg\" data-description=\"Aperol Spritz\" data-repin=\"\"><span class=\"wprm-recipe-icon wprm-recipe-pin-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" viewBox=\"0 0 24 24\"><g class=\"nc-icon-wrapper\" fill=\"#333333\"><path fill=\"#333333\" d=\"M12,0C5.4,0,0,5.4,0,12c0,5.1,3.2,9.4,7.6,11.2c-0.1-0.9-0.2-2.4,0-3.4c0.2-0.9,1.4-6,1.4-6S8.7,13,8.7,12 c0-1.7,1-2.9,2.2-2.9c1,0,1.5,0.8,1.5,1.7c0,1-0.7,2.6-1,4c-0.3,1.2,0.6,2.2,1.8,2.2c2.1,0,3.8-2.2,3.8-5.5c0-2.9-2.1-4.9-5-4.9 c-3.4,0-5.4,2.6-5.4,5.2c0,1,0.4,2.1,0.9,2.7c0.1,0.1,0.1,0.2,0.1,0.3c-0.1,0.4-0.3,1.2-0.3,1.4c-0.1,0.2-0.2,0.3-0.4,0.2 c-1.5-0.7-2.4-2.9-2.4-4.6c0-3.8,2.8-7.3,7.9-7.3c4.2,0,7.4,3,7.4,6.9c0,4.1-2.6,7.5-6.2,7.5c-1.2,0-2.4-0.6-2.8-1.4 c0,0-0.6,2.3-0.7,2.9c-0.3,1-1,2.3-1.5,3.1C9.6,23.8,10.8,24,12,24c6.6,0,12-5.4,12-12C24,5.4,18.6,0,12,0z\"><\/path><\/g><\/svg><\/span> Pin<\/a>\n\t\n<\/div>\n<h2 class=\"wprm-recipe-name wprm-block-text-bold\"><span class=\"ez-toc-section\" id=\"Aperol_Spritz\"><\/span>Aperol Spritz<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<div class=\"wprm-spacer\" style=\"height: 5px\"><\/div>\n<div class=\"wprm-recipe-summary wprm-block-text-normal\">O Aperol Spritz \u00e9 um dos drinks italianos mais cl\u00e1ssicos e que nunca sai de moda. Combina prosecco, aperitivo Aperol e \u00e1gua com g\u00e1s para uma bebida refrescante. Confira!<\/div>\n<div class=\"wprm-spacer\"><\/div>\n\n<div class=\"wprm-spacer\"><\/div>\n\n<div class=\"wprm-spacer\"><\/div>\n\n\n\n\n\n<div class=\"wprm-recipe-ingredients-container wprm-recipe-10027-ingredients-container wprm-block-text-normal wprm-ingredient-style-regular wprm-recipe-images-before\" data-recipe=\"10027\" data-servings=\"0\"><h3 class=\"wprm-recipe-header wprm-recipe-ingredients-header wprm-block-text-bold wprm-align-left wprm-header-decoration-none\" style=\"\">Ingredients<\/h3><div class=\"wprm-recipe-ingredient-group\"><ul class=\"wprm-recipe-ingredients\"><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"0\"><span class=\"wprm-recipe-ingredient-amount\">25<\/span>&#32;<span class=\"wprm-recipe-ingredient-unit\">ml<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">de \u00e1gua com g\u00e1s<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"1\"><span class=\"wprm-recipe-ingredient-amount\">50<\/span>&#32;<span class=\"wprm-recipe-ingredient-unit\">ml<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">de Aperol<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"2\"><span class=\"wprm-recipe-ingredient-amount\">75<\/span>&#32;<span class=\"wprm-recipe-ingredient-unit\">ml<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">de prosecco<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"3\"><span class=\"wprm-recipe-ingredient-amount\">1<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">fatia de laranja<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"4\"><span class=\"wprm-recipe-ingredient-name\">Gelo a gosto<\/span><\/li><\/ul><\/div><\/div>\n<div class=\"wprm-recipe-instructions-container wprm-recipe-10027-instructions-container wprm-block-text-normal\" data-recipe=\"10027\"><h3 class=\"wprm-recipe-header wprm-recipe-instructions-header wprm-block-text-bold wprm-align-left wprm-header-decoration-none\" style=\"\">Instructions<\/h3><div class=\"wprm-recipe-instruction-group\"><ul class=\"wprm-recipe-instructions\"><li id=\"wprm-recipe-10027-step-0-0\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\">Em uma ta\u00e7a, adicione os cubos de gelo e a fatia de laranja.<\/div><\/li><li id=\"wprm-recipe-10027-step-0-1\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\">Depois, inclua o Aperol, o prosecco e complete com \u00e1gua com g\u00e1s.<\/div><\/li><li id=\"wprm-recipe-10027-step-0-2\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\">Mexa delicadamente para finaliz\u00e1-lo.<\/div><\/li><\/ul><\/div><\/div>\n\n\n<\/div><\/div>\n<h2 aria-level=\"2\"><span class=\"ez-toc-section\" id=\"4_Limoncello_Spritz\"><\/span><b><span data-contrast=\"auto\">4. Limoncello Spritz<\/span><\/b><span data-ccp-props=\"{&quot;134245417&quot;:false,&quot;134245418&quot;:true,&quot;134245529&quot;:true}\">\u00a0<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span data-contrast=\"auto\">Em busca de <\/span><span data-contrast=\"none\">drinks com prosecco<\/span><span data-contrast=\"auto\">? Experimente preparar o Limoncello Spritz! Refrescante e muito f\u00e1cil de fazer, esse coquetel italiano \u00e9 a bebida perfeita para momentos de descontra\u00e7\u00e3o ao ar livre, como um almo\u00e7o, jantar ou piquenique de ver\u00e3o.<\/span><span data-ccp-props=\"{&quot;134245417&quot;:false}\">\u00a0<\/span><\/p>\n<div id=\"wprm-recipe-container-10044\" class=\"wprm-recipe-container\" data-recipe-id=\"10044\" data-servings=\"0\"><div class=\"wprm-recipe wprm-recipe-template-classic\"><div class=\"wprm-container-float-right\">\n\t<div class=\"wprm-recipe-image wprm-block-image-normal\"><img loading=\"lazy\" decoding=\"async\" style=\"border-width: 0px;border-style: solid;border-color: #666666;\" width=\"150\" height=\"150\" src=\"https:\/\/www.divvino.com.br\/blog\/wp-content\/uploads\/2023\/10\/limoncello-spritz-150x150.jpg\" class=\"attachment-150x150 size-150x150\" alt=\"Limoncello Spritz\u00a0\" srcset=\"https:\/\/www.divvino.com.br\/blog\/wp-content\/uploads\/2023\/10\/limoncello-spritz-150x150.jpg 150w, https:\/\/www.divvino.com.br\/blog\/wp-content\/uploads\/2023\/10\/limoncello-spritz-300x300.jpg 300w, https:\/\/www.divvino.com.br\/blog\/wp-content\/uploads\/2023\/10\/limoncello-spritz.jpg 500w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/div>\n\t<div class=\"wprm-spacer\" style=\"height: 5px\"><\/div>\n\t\n\t<div class=\"wprm-spacer\" style=\"height: 2px\"><\/div>\n\t<a href=\"https:\/\/www.divvino.com.br\/blog\/wprm_print\/limoncello-spritz\" style=\"color: #333333;\" class=\"wprm-recipe-print wprm-recipe-link wprm-print-recipe-shortcode wprm-block-text-normal\" data-recipe-id=\"10044\" data-template=\"\" target=\"_blank\" rel=\"nofollow\"><span class=\"wprm-recipe-icon wprm-recipe-print-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"16px\" height=\"16px\" viewBox=\"0 0 24 24\"><g ><path fill=\"#333333\" d=\"M19,5.09V1c0-0.552-0.448-1-1-1H6C5.448,0,5,0.448,5,1v4.09C2.167,5.569,0,8.033,0,11v7c0,0.552,0.448,1,1,1h4v4c0,0.552,0.448,1,1,1h12c0.552,0,1-0.448,1-1v-4h4c0.552,0,1-0.448,1-1v-7C24,8.033,21.833,5.569,19,5.09z M7,2h10v3H7V2z M17,22H7v-9h10V22z M18,10c-0.552,0-1-0.448-1-1c0-0.552,0.448-1,1-1s1,0.448,1,1C19,9.552,18.552,10,18,10z\"\/><\/g><\/svg><\/span> Print<\/a>\n\t<a href=\"https:\/\/www.pinterest.com\/pin\/create\/bookmarklet\/?url=https%3A%2F%2Fwww.divvino.com.br%2Fblog%2Fdrinks-com-prosecco%2F&amp;media=https%3A%2F%2Fwww.divvino.com.br%2Fblog%2Fwp-content%2Fuploads%2F2023%2F10%2Flimoncello-spritz.jpg&amp;description=Limoncello+Spritz&amp;is_video=false\" style=\"color: #333333;\" class=\"wprm-recipe-pin wprm-recipe-link wprm-block-text-normal\" target=\"_blank\" rel=\"nofollow noopener\" data-recipe=\"10044\" data-url=\"https:\/\/www.divvino.com.br\/blog\/drinks-com-prosecco\/\" data-media=\"https:\/\/www.divvino.com.br\/blog\/wp-content\/uploads\/2023\/10\/limoncello-spritz.jpg\" data-description=\"Limoncello Spritz\" data-repin=\"\"><span class=\"wprm-recipe-icon wprm-recipe-pin-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" viewBox=\"0 0 24 24\"><g class=\"nc-icon-wrapper\" fill=\"#333333\"><path fill=\"#333333\" d=\"M12,0C5.4,0,0,5.4,0,12c0,5.1,3.2,9.4,7.6,11.2c-0.1-0.9-0.2-2.4,0-3.4c0.2-0.9,1.4-6,1.4-6S8.7,13,8.7,12 c0-1.7,1-2.9,2.2-2.9c1,0,1.5,0.8,1.5,1.7c0,1-0.7,2.6-1,4c-0.3,1.2,0.6,2.2,1.8,2.2c2.1,0,3.8-2.2,3.8-5.5c0-2.9-2.1-4.9-5-4.9 c-3.4,0-5.4,2.6-5.4,5.2c0,1,0.4,2.1,0.9,2.7c0.1,0.1,0.1,0.2,0.1,0.3c-0.1,0.4-0.3,1.2-0.3,1.4c-0.1,0.2-0.2,0.3-0.4,0.2 c-1.5-0.7-2.4-2.9-2.4-4.6c0-3.8,2.8-7.3,7.9-7.3c4.2,0,7.4,3,7.4,6.9c0,4.1-2.6,7.5-6.2,7.5c-1.2,0-2.4-0.6-2.8-1.4 c0,0-0.6,2.3-0.7,2.9c-0.3,1-1,2.3-1.5,3.1C9.6,23.8,10.8,24,12,24c6.6,0,12-5.4,12-12C24,5.4,18.6,0,12,0z\"><\/path><\/g><\/svg><\/span> Pin<\/a>\n\t\n<\/div>\n<h2 class=\"wprm-recipe-name wprm-block-text-bold\"><span class=\"ez-toc-section\" id=\"Limoncello_Spritz\"><\/span>Limoncello Spritz<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<div class=\"wprm-spacer\" style=\"height: 5px\"><\/div>\n<div class=\"wprm-recipe-summary wprm-block-text-normal\">Limocello Spritz \u00e9 o significado de frescor e suavidade ao combinar o Limoncello com prosecco em dias quentes. Veja a receita!<\/div>\n<div class=\"wprm-spacer\"><\/div>\n\n<div class=\"wprm-spacer\"><\/div>\n\n<div class=\"wprm-spacer\"><\/div>\n\n\n\n\n\n<div class=\"wprm-recipe-ingredients-container wprm-recipe-10044-ingredients-container wprm-block-text-normal wprm-ingredient-style-regular wprm-recipe-images-before\" data-recipe=\"10044\" data-servings=\"0\"><h3 class=\"wprm-recipe-header wprm-recipe-ingredients-header wprm-block-text-bold wprm-align-left wprm-header-decoration-none\" style=\"\">Ingredients<\/h3><div class=\"wprm-recipe-ingredient-group\"><ul class=\"wprm-recipe-ingredients\"><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"0\"><span class=\"wprm-recipe-ingredient-amount\">30<\/span>&#32;<span class=\"wprm-recipe-ingredient-unit\">ml<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">de Limoncello<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"1\"><span class=\"wprm-recipe-ingredient-amount\">50<\/span>&#32;<span class=\"wprm-recipe-ingredient-unit\">ml<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">de \u00e1gua com g\u00e1s<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"2\"><span class=\"wprm-recipe-ingredient-amount\">120<\/span>&#32;<span class=\"wprm-recipe-ingredient-unit\">ml<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">de prosecco<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"3\"><span class=\"wprm-recipe-ingredient-name\">Gelo a gosto<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"4\"><span class=\"wprm-recipe-ingredient-amount\">1<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">lim\u00e3o-siciliano para decorar<\/span><\/li><\/ul><\/div><\/div>\n<div class=\"wprm-recipe-instructions-container wprm-recipe-10044-instructions-container wprm-block-text-normal\" data-recipe=\"10044\"><h3 class=\"wprm-recipe-header wprm-recipe-instructions-header wprm-block-text-bold wprm-align-left wprm-header-decoration-none\" style=\"\">Instructions<\/h3><div class=\"wprm-recipe-instruction-group\"><ul class=\"wprm-recipe-instructions\"><li id=\"wprm-recipe-10044-step-0-0\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\">Em uma ta\u00e7a grande, coloque o Limoncello e o prosecco. Misture delicadamente.<\/div><\/li><li id=\"wprm-recipe-10044-step-0-1\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\">Acrescente gelo, complete com \u00e1gua com g\u00e1s e mexa novamente.<\/div><\/li><li id=\"wprm-recipe-10044-step-0-2\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\">Decore com uma rodela ou casca de lim\u00e3o-siciliano e seu coquetel estar\u00e1 pronto!<\/div><\/li><\/ul><\/div><\/div>\n\n\n<\/div><\/div>\n<h2 aria-level=\"2\"><span class=\"ez-toc-section\" id=\"5_Kir_Royale\"><\/span><b><span data-contrast=\"auto\">5. Kir Royale<\/span><\/b><span data-ccp-props=\"{&quot;134245417&quot;:false,&quot;134245418&quot;:true,&quot;134245529&quot;:true}\">\u00a0<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span data-contrast=\"auto\">O Kir Royale \u00e9 um coquetel franc\u00eas criado em 1904. Trata-se de um <\/span><span data-contrast=\"none\">drink com espumante e frutas<\/span><span data-contrast=\"auto\"> vermelhas, ideal para quem gosta de bebidas f\u00e1ceis para apreciar em \u00e9pocas quentes.<\/span><span data-ccp-props=\"{&quot;134245417&quot;:false}\">\u00a0<\/span><\/p>\n<div id=\"wprm-recipe-container-10029\" class=\"wprm-recipe-container\" data-recipe-id=\"10029\" data-servings=\"0\"><div class=\"wprm-recipe wprm-recipe-template-classic\"><div class=\"wprm-container-float-right\">\n\t<div class=\"wprm-recipe-image wprm-block-image-normal\"><img loading=\"lazy\" decoding=\"async\" style=\"border-width: 0px;border-style: solid;border-color: #666666;\" width=\"150\" height=\"150\" src=\"https:\/\/www.divvino.com.br\/blog\/wp-content\/uploads\/2023\/09\/drinks-com-prosecco-kir-royal-150x150.jpg\" class=\"attachment-150x150 size-150x150\" alt=\"drinks com Prosecco - Kir Royal\" \/><\/div>\n\t<div class=\"wprm-spacer\" style=\"height: 5px\"><\/div>\n\t\n\t<div class=\"wprm-spacer\" style=\"height: 2px\"><\/div>\n\t<a href=\"https:\/\/www.divvino.com.br\/blog\/wprm_print\/kir-royale\" style=\"color: #333333;\" class=\"wprm-recipe-print wprm-recipe-link wprm-print-recipe-shortcode wprm-block-text-normal\" data-recipe-id=\"10029\" data-template=\"\" target=\"_blank\" rel=\"nofollow\"><span class=\"wprm-recipe-icon wprm-recipe-print-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"16px\" height=\"16px\" viewBox=\"0 0 24 24\"><g ><path fill=\"#333333\" d=\"M19,5.09V1c0-0.552-0.448-1-1-1H6C5.448,0,5,0.448,5,1v4.09C2.167,5.569,0,8.033,0,11v7c0,0.552,0.448,1,1,1h4v4c0,0.552,0.448,1,1,1h12c0.552,0,1-0.448,1-1v-4h4c0.552,0,1-0.448,1-1v-7C24,8.033,21.833,5.569,19,5.09z M7,2h10v3H7V2z M17,22H7v-9h10V22z M18,10c-0.552,0-1-0.448-1-1c0-0.552,0.448-1,1-1s1,0.448,1,1C19,9.552,18.552,10,18,10z\"\/><\/g><\/svg><\/span> Print<\/a>\n\t<a href=\"https:\/\/www.pinterest.com\/pin\/create\/bookmarklet\/?url=https%3A%2F%2Fwww.divvino.com.br%2Fblog%2Fdrinks-com-prosecco%2F&amp;media=https%3A%2F%2Fwww.divvino.com.br%2Fblog%2Fwp-content%2Fuploads%2F2023%2F09%2Fdrinks-com-prosecco-kir-royal.jpg&amp;description=Kir+Royale&amp;is_video=false\" style=\"color: #333333;\" class=\"wprm-recipe-pin wprm-recipe-link wprm-block-text-normal\" target=\"_blank\" rel=\"nofollow noopener\" data-recipe=\"10029\" data-url=\"https:\/\/www.divvino.com.br\/blog\/drinks-com-prosecco\/\" data-media=\"https:\/\/www.divvino.com.br\/blog\/wp-content\/uploads\/2023\/09\/drinks-com-prosecco-kir-royal.jpg\" data-description=\"Kir Royale\" data-repin=\"\"><span class=\"wprm-recipe-icon wprm-recipe-pin-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" viewBox=\"0 0 24 24\"><g class=\"nc-icon-wrapper\" fill=\"#333333\"><path fill=\"#333333\" d=\"M12,0C5.4,0,0,5.4,0,12c0,5.1,3.2,9.4,7.6,11.2c-0.1-0.9-0.2-2.4,0-3.4c0.2-0.9,1.4-6,1.4-6S8.7,13,8.7,12 c0-1.7,1-2.9,2.2-2.9c1,0,1.5,0.8,1.5,1.7c0,1-0.7,2.6-1,4c-0.3,1.2,0.6,2.2,1.8,2.2c2.1,0,3.8-2.2,3.8-5.5c0-2.9-2.1-4.9-5-4.9 c-3.4,0-5.4,2.6-5.4,5.2c0,1,0.4,2.1,0.9,2.7c0.1,0.1,0.1,0.2,0.1,0.3c-0.1,0.4-0.3,1.2-0.3,1.4c-0.1,0.2-0.2,0.3-0.4,0.2 c-1.5-0.7-2.4-2.9-2.4-4.6c0-3.8,2.8-7.3,7.9-7.3c4.2,0,7.4,3,7.4,6.9c0,4.1-2.6,7.5-6.2,7.5c-1.2,0-2.4-0.6-2.8-1.4 c0,0-0.6,2.3-0.7,2.9c-0.3,1-1,2.3-1.5,3.1C9.6,23.8,10.8,24,12,24c6.6,0,12-5.4,12-12C24,5.4,18.6,0,12,0z\"><\/path><\/g><\/svg><\/span> Pin<\/a>\n\t\n<\/div>\n<h2 class=\"wprm-recipe-name wprm-block-text-bold\"><span class=\"ez-toc-section\" id=\"Kir_Royale\"><\/span>Kir Royale<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<div class=\"wprm-spacer\" style=\"height: 5px\"><\/div>\n<div class=\"wprm-recipe-summary wprm-block-text-normal\">O Kir Royale \u00e9 um drink de frutas vermelhas com espumante. Uma del\u00edcia para se refrescar em \u00e9pocas quentes. Veja!<\/div>\n<div class=\"wprm-spacer\"><\/div>\n\n<div class=\"wprm-spacer\"><\/div>\n\n<div class=\"wprm-spacer\"><\/div>\n\n\n\n\n\n<div class=\"wprm-recipe-ingredients-container wprm-recipe-10029-ingredients-container wprm-block-text-normal wprm-ingredient-style-regular wprm-recipe-images-before\" data-recipe=\"10029\" data-servings=\"0\"><h3 class=\"wprm-recipe-header wprm-recipe-ingredients-header wprm-block-text-bold wprm-align-left wprm-header-decoration-none\" style=\"\">Ingredients<\/h3><div class=\"wprm-recipe-ingredient-group\"><ul class=\"wprm-recipe-ingredients\"><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"0\"><span class=\"wprm-recipe-ingredient-amount\">15<\/span>&#32;<span class=\"wprm-recipe-ingredient-unit\">ml<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">de creme de cassis<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"1\"><span class=\"wprm-recipe-ingredient-name\">Espumante para completar<\/span>&#32;<span class=\"wprm-recipe-ingredient-notes wprm-recipe-ingredient-notes-faded\">como champanhe ou prosecco<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"2\"><span class=\"wprm-recipe-ingredient-name\">Frutas vermelhas para decorar<\/span><\/li><\/ul><\/div><\/div>\n<div class=\"wprm-recipe-instructions-container wprm-recipe-10029-instructions-container wprm-block-text-normal\" data-recipe=\"10029\"><h3 class=\"wprm-recipe-header wprm-recipe-instructions-header wprm-block-text-bold wprm-align-left wprm-header-decoration-none\" style=\"\">Instructions<\/h3><div class=\"wprm-recipe-instruction-group\"><ul class=\"wprm-recipe-instructions\"><li id=\"wprm-recipe-10029-step-0-0\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\">Em uma ta\u00e7a fl\u00fbte, adicione o creme de cassis.<\/div><\/li><li id=\"wprm-recipe-10029-step-0-1\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\">Complete com o espumante da sua prefer\u00eancia.<\/div><\/li><li id=\"wprm-recipe-10029-step-0-2\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\">Decore com as frutas vermelhas de sua prefer\u00eancia, como morango, melancia, cereja, framboesa, amora, uva, entre outras. Est\u00e1 pronto para servir!<\/div><\/li><\/ul><\/div><\/div>\n\n\n<\/div><\/div>\n<h2 aria-level=\"2\"><span class=\"ez-toc-section\" id=\"6_Negroni_Sbagliato\"><\/span><b><span data-contrast=\"auto\">6. Negroni Sbagliato<\/span><\/b><span data-ccp-props=\"{&quot;134245417&quot;:false,&quot;134245418&quot;:true,&quot;134245529&quot;:true}\">\u00a0<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span data-contrast=\"auto\">O <\/span><a href=\"https:\/\/www.divvino.com.br\/blog\/drinks-com-campari\/\" target=\"_blank\" rel=\"noopener\"><span data-contrast=\"none\">Negroni<\/span><\/a><span data-contrast=\"auto\"> Sbagliato \u00e9 uma vers\u00e3o adaptada do cl\u00e1ssico coquetel italiano. <\/span><span data-contrast=\"none\">O termo &#8220;Sbagliato&#8221; significa &#8220;errado&#8221; em italiano, refletindo a origem do drink, que foi criado por acidente em 1972 pelo barman Mirko Stocchetto.\u00a0<\/span><span data-ccp-props=\"{&quot;134245417&quot;:false}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"none\">Diferente do <\/span><a href=\"https:\/\/www.divvino.com.br\/aperitivo-campari-bitter-748ml-5207810\/p\/?utm_source=blog&amp;utm_medium=post&amp;utm_content=campari&amp;utm_campaign=drinks-com-espumante\" target=\"_blank\" rel=\"noopener\"><span data-contrast=\"none\">tradicional<\/span><\/a><span data-contrast=\"none\">, <\/span><span data-contrast=\"auto\">no lugar do gin, adiciona-se espumante.<\/span><span data-contrast=\"none\"> Essa varia\u00e7\u00e3o resulta em um coquetel mais leve e efervescente, ideal para quem prefere uma bebida com teor alco\u00f3lico mais baixo.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;134245417&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:1,&quot;335551620&quot;:1,&quot;335559685&quot;:0,&quot;335559737&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p>\n<div id=\"wprm-recipe-container-10046\" class=\"wprm-recipe-container\" data-recipe-id=\"10046\" data-servings=\"0\"><div class=\"wprm-recipe wprm-recipe-template-classic\"><div class=\"wprm-container-float-right\">\n\t<div class=\"wprm-recipe-image wprm-block-image-normal\"><img loading=\"lazy\" decoding=\"async\" style=\"border-width: 0px;border-style: solid;border-color: #666666;\" width=\"150\" height=\"150\" src=\"https:\/\/www.divvino.com.br\/blog\/wp-content\/uploads\/2023\/10\/negroni-sbagliato-150x150.jpg\" class=\"attachment-150x150 size-150x150\" alt=\"Negroni Sbagliato\u00a0\" srcset=\"https:\/\/www.divvino.com.br\/blog\/wp-content\/uploads\/2023\/10\/negroni-sbagliato-150x150.jpg 150w, https:\/\/www.divvino.com.br\/blog\/wp-content\/uploads\/2023\/10\/negroni-sbagliato-300x300.jpg 300w, https:\/\/www.divvino.com.br\/blog\/wp-content\/uploads\/2023\/10\/negroni-sbagliato.jpg 500w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/div>\n\t<div class=\"wprm-spacer\" style=\"height: 5px\"><\/div>\n\t\n\t<div class=\"wprm-spacer\" style=\"height: 2px\"><\/div>\n\t<a href=\"https:\/\/www.divvino.com.br\/blog\/wprm_print\/negroni-sbagliato-2\" style=\"color: #333333;\" class=\"wprm-recipe-print wprm-recipe-link wprm-print-recipe-shortcode wprm-block-text-normal\" data-recipe-id=\"10046\" data-template=\"\" target=\"_blank\" rel=\"nofollow\"><span class=\"wprm-recipe-icon wprm-recipe-print-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"16px\" height=\"16px\" viewBox=\"0 0 24 24\"><g ><path fill=\"#333333\" d=\"M19,5.09V1c0-0.552-0.448-1-1-1H6C5.448,0,5,0.448,5,1v4.09C2.167,5.569,0,8.033,0,11v7c0,0.552,0.448,1,1,1h4v4c0,0.552,0.448,1,1,1h12c0.552,0,1-0.448,1-1v-4h4c0.552,0,1-0.448,1-1v-7C24,8.033,21.833,5.569,19,5.09z M7,2h10v3H7V2z M17,22H7v-9h10V22z M18,10c-0.552,0-1-0.448-1-1c0-0.552,0.448-1,1-1s1,0.448,1,1C19,9.552,18.552,10,18,10z\"\/><\/g><\/svg><\/span> Print<\/a>\n\t<a href=\"https:\/\/www.pinterest.com\/pin\/create\/bookmarklet\/?url=https%3A%2F%2Fwww.divvino.com.br%2Fblog%2Fdrinks-com-prosecco%2F&amp;media=https%3A%2F%2Fwww.divvino.com.br%2Fblog%2Fwp-content%2Fuploads%2F2023%2F10%2Fnegroni-sbagliato.jpg&amp;description=Negroni+Sbagliato&amp;is_video=false\" style=\"color: #333333;\" class=\"wprm-recipe-pin wprm-recipe-link wprm-block-text-normal\" target=\"_blank\" rel=\"nofollow noopener\" data-recipe=\"10046\" data-url=\"https:\/\/www.divvino.com.br\/blog\/drinks-com-prosecco\/\" data-media=\"https:\/\/www.divvino.com.br\/blog\/wp-content\/uploads\/2023\/10\/negroni-sbagliato.jpg\" data-description=\"Negroni Sbagliato\" data-repin=\"\"><span class=\"wprm-recipe-icon wprm-recipe-pin-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" viewBox=\"0 0 24 24\"><g class=\"nc-icon-wrapper\" fill=\"#333333\"><path fill=\"#333333\" d=\"M12,0C5.4,0,0,5.4,0,12c0,5.1,3.2,9.4,7.6,11.2c-0.1-0.9-0.2-2.4,0-3.4c0.2-0.9,1.4-6,1.4-6S8.7,13,8.7,12 c0-1.7,1-2.9,2.2-2.9c1,0,1.5,0.8,1.5,1.7c0,1-0.7,2.6-1,4c-0.3,1.2,0.6,2.2,1.8,2.2c2.1,0,3.8-2.2,3.8-5.5c0-2.9-2.1-4.9-5-4.9 c-3.4,0-5.4,2.6-5.4,5.2c0,1,0.4,2.1,0.9,2.7c0.1,0.1,0.1,0.2,0.1,0.3c-0.1,0.4-0.3,1.2-0.3,1.4c-0.1,0.2-0.2,0.3-0.4,0.2 c-1.5-0.7-2.4-2.9-2.4-4.6c0-3.8,2.8-7.3,7.9-7.3c4.2,0,7.4,3,7.4,6.9c0,4.1-2.6,7.5-6.2,7.5c-1.2,0-2.4-0.6-2.8-1.4 c0,0-0.6,2.3-0.7,2.9c-0.3,1-1,2.3-1.5,3.1C9.6,23.8,10.8,24,12,24c6.6,0,12-5.4,12-12C24,5.4,18.6,0,12,0z\"><\/path><\/g><\/svg><\/span> Pin<\/a>\n\t\n<\/div>\n<h2 class=\"wprm-recipe-name wprm-block-text-bold\"><span class=\"ez-toc-section\" id=\"Negroni_Sbagliato\"><\/span>Negroni Sbagliato<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<div class=\"wprm-spacer\" style=\"height: 5px\"><\/div>\n<div class=\"wprm-recipe-summary wprm-block-text-normal\">Negroni Sbagliato \u00e9 uma adapata\u00e7\u00e3o do cl\u00e1ssico, com espumante no lugar do gin, proporcionando num drink mais leve e menos alco\u00f3lico. Veja seu preparo!<\/div>\n<div class=\"wprm-spacer\"><\/div>\n\n<div class=\"wprm-spacer\"><\/div>\n\n<div class=\"wprm-spacer\"><\/div>\n\n\n\n\n\n<div class=\"wprm-recipe-ingredients-container wprm-recipe-10046-ingredients-container wprm-block-text-normal wprm-ingredient-style-regular wprm-recipe-images-before\" data-recipe=\"10046\" data-servings=\"0\"><h3 class=\"wprm-recipe-header wprm-recipe-ingredients-header wprm-block-text-bold wprm-align-left wprm-header-decoration-none\" style=\"\">Ingredients<\/h3><div class=\"wprm-recipe-ingredient-group\"><ul class=\"wprm-recipe-ingredients\"><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"0\"><span class=\"wprm-recipe-ingredient-amount\">30<\/span>&#32;<span class=\"wprm-recipe-ingredient-unit\">ml<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">de Vermute doce<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"1\"><span class=\"wprm-recipe-ingredient-amount\">30<\/span>&#32;<span class=\"wprm-recipe-ingredient-unit\">ml<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">de Campari<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"2\"><span class=\"wprm-recipe-ingredient-name\">Espumante para completar<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"3\"><span class=\"wprm-recipe-ingredient-name\">Casca de laranja<\/span><\/li><\/ul><\/div><\/div>\n<div class=\"wprm-recipe-instructions-container wprm-recipe-10046-instructions-container wprm-block-text-normal\" data-recipe=\"10046\"><h3 class=\"wprm-recipe-header wprm-recipe-instructions-header wprm-block-text-bold wprm-align-left wprm-header-decoration-none\" style=\"\">Instructions<\/h3><div class=\"wprm-recipe-instruction-group\"><ul class=\"wprm-recipe-instructions\"><li id=\"wprm-recipe-10046-step-0-0\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\">Em um copo alto ou uma ta\u00e7a, adicione o Vermute, o Campari e o gelo.<\/div><\/li><li id=\"wprm-recipe-10046-step-0-1\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\">Complete com espumante.<\/div><\/li><li id=\"wprm-recipe-10046-step-0-2\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\">Adicione uma casca de laranja para finalizar.<\/div><\/li><\/ul><\/div><\/div>\n\n\n<\/div><\/div>\n<h2 aria-level=\"2\"><span class=\"ez-toc-section\" id=\"7_French_75\"><\/span><b><span data-contrast=\"none\">7. French 75\u00a0<\/span><\/b><span data-ccp-props=\"{&quot;134245417&quot;:false,&quot;134245418&quot;:true,&quot;134245529&quot;:true}\">\u00a0<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span data-contrast=\"none\">O French 75 \u00e9 um <\/span><span data-contrast=\"none\">drink com champanhe<\/span><span data-contrast=\"none\">, gin, suco de lim\u00e3o e a\u00e7\u00facar. A bebida tem esse nome inspirado em um canh\u00e3o de artilharia francesa. \u00c9 f\u00e1cil de beber e conta com alto n\u00edvel de teor alco\u00f3lica. <\/span><span data-contrast=\"none\">pois \u00e9 f\u00e1cil de beber e &#8220;derrubar&#8221;<\/span> <span data-contrast=\"none\">a<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;134245417&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:1,&quot;335551620&quot;:1,&quot;335559685&quot;:0,&quot;335559737&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"none\">O coquetel apresenta um equil\u00edbrio de sabores, com o toque c\u00edtrico e o dul\u00e7or do a\u00e7\u00facar harmonizando com o <\/span><a href=\"https:\/\/www.divvino.com.br\/gin-tanqueray-london-dry-750ml-172014\/p\/?utm_source=blog&amp;utm_medium=post&amp;utm_content=gin-tanqueray&amp;utm_campaign=drinks-com-espumante\" target=\"_blank\" rel=\"noopener\"><span data-contrast=\"none\">gin<\/span><\/a><span data-contrast=\"none\"> e adicionando efervesc\u00eancia com o espumante. O drink \u00e9 muito arom\u00e1tico, proporcionando uma experi\u00eancia olfativa refrescante. Confira o passo a passo do canal <\/span><a href=\"https:\/\/www.youtube.com\/@etomedrink8526\" target=\"_blank\" rel=\"noopener\"><span data-contrast=\"none\">\u201cE Tome Drink\u201d<\/span><\/a><span data-contrast=\"none\">!\u00a0<\/span><span data-ccp-props=\"{&quot;134245417&quot;:false}\">\u00a0<\/span><\/p>\n<div id=\"wprm-recipe-container-10031\" class=\"wprm-recipe-container\" data-recipe-id=\"10031\" data-servings=\"0\"><div class=\"wprm-recipe wprm-recipe-template-classic\"><div class=\"wprm-container-float-right\">\n\t\n\t<div class=\"wprm-spacer\" style=\"height: 5px\"><\/div>\n\t\n\t<div class=\"wprm-spacer\" style=\"height: 2px\"><\/div>\n\t<a href=\"https:\/\/www.divvino.com.br\/blog\/wprm_print\/french-75\" style=\"color: #333333;\" class=\"wprm-recipe-print wprm-recipe-link wprm-print-recipe-shortcode wprm-block-text-normal\" data-recipe-id=\"10031\" data-template=\"\" target=\"_blank\" rel=\"nofollow\"><span class=\"wprm-recipe-icon wprm-recipe-print-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"16px\" height=\"16px\" viewBox=\"0 0 24 24\"><g ><path fill=\"#333333\" d=\"M19,5.09V1c0-0.552-0.448-1-1-1H6C5.448,0,5,0.448,5,1v4.09C2.167,5.569,0,8.033,0,11v7c0,0.552,0.448,1,1,1h4v4c0,0.552,0.448,1,1,1h12c0.552,0,1-0.448,1-1v-4h4c0.552,0,1-0.448,1-1v-7C24,8.033,21.833,5.569,19,5.09z M7,2h10v3H7V2z M17,22H7v-9h10V22z M18,10c-0.552,0-1-0.448-1-1c0-0.552,0.448-1,1-1s1,0.448,1,1C19,9.552,18.552,10,18,10z\"\/><\/g><\/svg><\/span> Print<\/a>\n\t\n\t\n<\/div>\n<h2 class=\"wprm-recipe-name wprm-block-text-bold\"><span class=\"ez-toc-section\" id=\"French_75\"><\/span>French 75<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<div class=\"wprm-spacer\" style=\"height: 5px\"><\/div>\n<div class=\"wprm-recipe-summary wprm-block-text-normal\">Um cl\u00e1ssico franc\u00eas refrescante, arom\u00e1tico com sabores muito equilibrados, o French 75 vai fazer sucesso durante os dias mais quentes. Veja como preparar!<\/div>\n<div class=\"wprm-spacer\"><\/div>\n\n<div class=\"wprm-spacer\"><\/div>\n\n<div class=\"wprm-spacer\"><\/div>\n\n\n\n\n\n<div class=\"wprm-recipe-ingredients-container wprm-recipe-10031-ingredients-container wprm-block-text-normal wprm-ingredient-style-regular wprm-recipe-images-before\" data-recipe=\"10031\" data-servings=\"0\"><h3 class=\"wprm-recipe-header wprm-recipe-ingredients-header wprm-block-text-bold wprm-align-left wprm-header-decoration-none\" style=\"\">Ingredients<\/h3><div class=\"wprm-recipe-ingredient-group\"><ul class=\"wprm-recipe-ingredients\"><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"0\"><span class=\"wprm-recipe-ingredient-amount\">15<\/span>&#32;<span class=\"wprm-recipe-ingredient-unit\">ml<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">de xarope de a\u00e7\u00facar<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"1\"><span class=\"wprm-recipe-ingredient-amount\">15<\/span>&#32;<span class=\"wprm-recipe-ingredient-unit\">ml<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">de suco de lim\u00e3o siciliano<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"2\"><span class=\"wprm-recipe-ingredient-amount\">60<\/span>&#32;<span class=\"wprm-recipe-ingredient-unit\">ml<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">de gin<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"3\"><span class=\"wprm-recipe-ingredient-name\">Completar com champanhe ou outro espumante brut<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"4\"><span class=\"wprm-recipe-ingredient-name\">Gelo a gosto<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"5\"><span class=\"wprm-recipe-ingredient-name\">Casca de lim\u00e3o-siciliano para decorar<\/span><\/li><\/ul><\/div><\/div>\n<div class=\"wprm-recipe-instructions-container wprm-recipe-10031-instructions-container wprm-block-text-normal\" data-recipe=\"10031\"><h3 class=\"wprm-recipe-header wprm-recipe-instructions-header wprm-block-text-bold wprm-align-left wprm-header-decoration-none\" style=\"\">Instructions<\/h3><div class=\"wprm-recipe-instruction-group\"><ul class=\"wprm-recipe-instructions\"><li id=\"wprm-recipe-10031-step-0-0\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\">Em uma coqueteleira, adicione o xarope de a\u00e7\u00facar, o suco de lim\u00e3o siciliano e o gin.<\/div><\/li><li id=\"wprm-recipe-10031-step-0-1\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\">Inclua gelo na coqueteleira e bata at\u00e9 \"suar\" o lado de fora do metal.<\/div><\/li><li id=\"wprm-recipe-10031-step-0-2\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\">Sirva em uma ta\u00e7a fl\u00fbte, com a casca de lim\u00e3o-siciliano dentro.<\/div><\/li><li id=\"wprm-recipe-10031-step-0-3\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\">Complete com champanhe ou outro espumante seco e est\u00e1 pronto para beber.<\/div><\/li><\/ul><\/div><\/div>\n<div id=\"recipe-video\"><\/div><div id=\"wprm-recipe-video-container-10031\" class=\"wprm-recipe-video-container\"><h3 class=\"wprm-recipe-header wprm-recipe-video-header wprm-block-text-bold wprm-align-left wprm-header-decoration-none\" style=\"\">Video<\/h3><div class=\"wprm-recipe-video\"><a href=\"https:\/\/youtu.be\/exYadvhgfF4\">https:\/\/youtu.be\/exYadvhgfF4<\/a><\/div><\/div>\n\n<\/div><\/div>\n<p><iframe loading=\"lazy\" title=\"Como Fazer French 75 (Casablanca) | E Tome Drink!\" src=\"https:\/\/www.youtube.com\/embed\/exYadvhgfF4\" width=\"866\" height=\"487\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h2 aria-level=\"2\"><span class=\"ez-toc-section\" id=\"8_Death_in_Venice\"><\/span><b><span data-contrast=\"auto\">8. Death in Venice\u00a0<\/span><\/b><span data-ccp-props=\"{&quot;134245417&quot;:false,&quot;134245418&quot;:true,&quot;134245529&quot;:true}\">\u00a0<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span data-contrast=\"auto\">O Death <\/span><span data-contrast=\"none\">in<\/span><span data-contrast=\"auto\"> Venice \u00e9 um coquetel mais recente. Foi criado em Londres, em 2010, por Tony Colebrooke Row. \u00c9 uma op\u00e7\u00e3o para quem aprecia drinks mais secos e intensos.<\/span><span data-ccp-props=\"{&quot;134245417&quot;:false}\">\u00a0<\/span><\/p>\n<div id=\"wprm-recipe-container-10048\" class=\"wprm-recipe-container\" data-recipe-id=\"10048\" data-servings=\"0\"><div class=\"wprm-recipe wprm-recipe-template-classic\"><div class=\"wprm-container-float-right\">\n\t<div class=\"wprm-recipe-image wprm-block-image-normal\"><img loading=\"lazy\" decoding=\"async\" style=\"border-width: 0px;border-style: solid;border-color: #666666;\" width=\"150\" height=\"150\" src=\"https:\/\/www.divvino.com.br\/blog\/wp-content\/uploads\/2023\/10\/death-in-venice-150x150.jpg\" class=\"attachment-150x150 size-150x150\" alt=\"Death in Venice\u00a0\" srcset=\"https:\/\/www.divvino.com.br\/blog\/wp-content\/uploads\/2023\/10\/death-in-venice-150x150.jpg 150w, https:\/\/www.divvino.com.br\/blog\/wp-content\/uploads\/2023\/10\/death-in-venice-300x300.jpg 300w, https:\/\/www.divvino.com.br\/blog\/wp-content\/uploads\/2023\/10\/death-in-venice.jpg 500w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/div>\n\t<div class=\"wprm-spacer\" style=\"height: 5px\"><\/div>\n\t\n\t<div class=\"wprm-spacer\" style=\"height: 2px\"><\/div>\n\t<a href=\"https:\/\/www.divvino.com.br\/blog\/wprm_print\/death-in-venice\" style=\"color: #333333;\" class=\"wprm-recipe-print wprm-recipe-link wprm-print-recipe-shortcode wprm-block-text-normal\" data-recipe-id=\"10048\" data-template=\"\" target=\"_blank\" rel=\"nofollow\"><span class=\"wprm-recipe-icon wprm-recipe-print-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"16px\" height=\"16px\" viewBox=\"0 0 24 24\"><g ><path fill=\"#333333\" d=\"M19,5.09V1c0-0.552-0.448-1-1-1H6C5.448,0,5,0.448,5,1v4.09C2.167,5.569,0,8.033,0,11v7c0,0.552,0.448,1,1,1h4v4c0,0.552,0.448,1,1,1h12c0.552,0,1-0.448,1-1v-4h4c0.552,0,1-0.448,1-1v-7C24,8.033,21.833,5.569,19,5.09z M7,2h10v3H7V2z M17,22H7v-9h10V22z M18,10c-0.552,0-1-0.448-1-1c0-0.552,0.448-1,1-1s1,0.448,1,1C19,9.552,18.552,10,18,10z\"\/><\/g><\/svg><\/span> Print<\/a>\n\t<a href=\"https:\/\/www.pinterest.com\/pin\/create\/bookmarklet\/?url=https%3A%2F%2Fwww.divvino.com.br%2Fblog%2Fdrinks-com-prosecco%2F&amp;media=https%3A%2F%2Fwww.divvino.com.br%2Fblog%2Fwp-content%2Fuploads%2F2023%2F10%2Fdeath-in-venice.jpg&amp;description=Death+in+Venice&amp;is_video=false\" style=\"color: #333333;\" class=\"wprm-recipe-pin wprm-recipe-link wprm-block-text-normal\" target=\"_blank\" rel=\"nofollow noopener\" data-recipe=\"10048\" data-url=\"https:\/\/www.divvino.com.br\/blog\/drinks-com-prosecco\/\" data-media=\"https:\/\/www.divvino.com.br\/blog\/wp-content\/uploads\/2023\/10\/death-in-venice.jpg\" data-description=\"Death in Venice\" data-repin=\"\"><span class=\"wprm-recipe-icon wprm-recipe-pin-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" viewBox=\"0 0 24 24\"><g class=\"nc-icon-wrapper\" fill=\"#333333\"><path fill=\"#333333\" d=\"M12,0C5.4,0,0,5.4,0,12c0,5.1,3.2,9.4,7.6,11.2c-0.1-0.9-0.2-2.4,0-3.4c0.2-0.9,1.4-6,1.4-6S8.7,13,8.7,12 c0-1.7,1-2.9,2.2-2.9c1,0,1.5,0.8,1.5,1.7c0,1-0.7,2.6-1,4c-0.3,1.2,0.6,2.2,1.8,2.2c2.1,0,3.8-2.2,3.8-5.5c0-2.9-2.1-4.9-5-4.9 c-3.4,0-5.4,2.6-5.4,5.2c0,1,0.4,2.1,0.9,2.7c0.1,0.1,0.1,0.2,0.1,0.3c-0.1,0.4-0.3,1.2-0.3,1.4c-0.1,0.2-0.2,0.3-0.4,0.2 c-1.5-0.7-2.4-2.9-2.4-4.6c0-3.8,2.8-7.3,7.9-7.3c4.2,0,7.4,3,7.4,6.9c0,4.1-2.6,7.5-6.2,7.5c-1.2,0-2.4-0.6-2.8-1.4 c0,0-0.6,2.3-0.7,2.9c-0.3,1-1,2.3-1.5,3.1C9.6,23.8,10.8,24,12,24c6.6,0,12-5.4,12-12C24,5.4,18.6,0,12,0z\"><\/path><\/g><\/svg><\/span> Pin<\/a>\n\t\n<\/div>\n<h2 class=\"wprm-recipe-name wprm-block-text-bold\"><span class=\"ez-toc-section\" id=\"Death_in_Venice\"><\/span>Death in Venice<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<div class=\"wprm-spacer\" style=\"height: 5px\"><\/div>\n<div class=\"wprm-recipe-summary wprm-block-text-normal\">Death in Venice \u00e9 um drink contempor\u00e2neo. Um excelente coquetel para quem prefere um sabor mais seco e intenso. Veja como preparar!<\/div>\n<div class=\"wprm-spacer\"><\/div>\n\n<div class=\"wprm-spacer\"><\/div>\n\n<div class=\"wprm-spacer\"><\/div>\n\n\n\n\n\n<div class=\"wprm-recipe-ingredients-container wprm-recipe-10048-ingredients-container wprm-block-text-normal wprm-ingredient-style-regular wprm-recipe-images-before\" data-recipe=\"10048\" data-servings=\"0\"><h3 class=\"wprm-recipe-header wprm-recipe-ingredients-header wprm-block-text-bold wprm-align-left wprm-header-decoration-none\" style=\"\">Ingredients<\/h3><div class=\"wprm-recipe-ingredient-group\"><ul class=\"wprm-recipe-ingredients\"><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"0\"><span class=\"wprm-recipe-ingredient-amount\">3<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">gotas de bitter de grapefruit<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"1\"><span class=\"wprm-recipe-ingredient-amount\">20<\/span>&#32;<span class=\"wprm-recipe-ingredient-unit\">ml<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">de Campari<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"2\"><span class=\"wprm-recipe-ingredient-amount\">150<\/span>&#32;<span class=\"wprm-recipe-ingredient-unit\">ml<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">de prosecco<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"3\"><span class=\"wprm-recipe-ingredient-name\">Casca de laranja para decora\u00e7\u00e3o<\/span>&#32;<span class=\"wprm-recipe-ingredient-notes wprm-recipe-ingredient-notes-faded\">opcional<\/span><\/li><\/ul><\/div><\/div>\n<div class=\"wprm-recipe-instructions-container wprm-recipe-10048-instructions-container wprm-block-text-normal\" data-recipe=\"10048\"><h3 class=\"wprm-recipe-header wprm-recipe-instructions-header wprm-block-text-bold wprm-align-left wprm-header-decoration-none\" style=\"\">Instructions<\/h3><div class=\"wprm-recipe-instruction-group\"><ul class=\"wprm-recipe-instructions\"><li id=\"wprm-recipe-10048-step-0-0\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\">Comece resfriando uma ta\u00e7a fl\u00fbte.<\/div><\/li><li id=\"wprm-recipe-10048-step-0-1\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\">Depois, inclua o Campari e as gotas de bitter.<\/div><\/li><li id=\"wprm-recipe-10048-step-0-2\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\">Complete com prosecco e, se quiser, decore com uma casca de laranja.<\/div><\/li><\/ul><\/div><\/div>\n\n\n<\/div><\/div>\n<h2 aria-level=\"2\"><span class=\"ez-toc-section\" id=\"9_Champagne_cocktail\"><\/span><b><span data-contrast=\"none\">9. Champagne <\/span><\/b><b><span data-contrast=\"none\">co<\/span><\/b><b><span data-contrast=\"none\">cktail<\/span><\/b><b><span data-contrast=\"none\">\u00a0<\/span><\/b><span data-ccp-props=\"{&quot;134245417&quot;:false,&quot;134245418&quot;:true,&quot;134245529&quot;:true}\">\u00a0<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span data-contrast=\"none\">Uma das <\/span><span data-contrast=\"none\">bebidas com champanhe<\/span><span data-contrast=\"none\"> \u00e9 o Champagne <\/span><span data-contrast=\"none\">cocktail<\/span><span data-contrast=\"none\">,<\/span><span data-contrast=\"none\"> drink cl\u00e1ssico, elegante e refrescante que real\u00e7a o sabor do espumante com um toque sutil de a\u00e7\u00facar e bitters. Ele \u00e9 perfeito para celebra\u00e7\u00f5es e ocasi\u00f5es especiais.<\/span><span data-ccp-props=\"{&quot;134245417&quot;:false}\">\u00a0<\/span><\/p>\n<div id=\"wprm-recipe-container-10050\" class=\"wprm-recipe-container\" data-recipe-id=\"10050\" data-servings=\"0\"><div class=\"wprm-recipe wprm-recipe-template-classic\"><div class=\"wprm-container-float-right\">\n\t<div class=\"wprm-recipe-image wprm-block-image-normal\"><img loading=\"lazy\" decoding=\"async\" style=\"border-width: 0px;border-style: solid;border-color: #666666;\" width=\"150\" height=\"150\" src=\"https:\/\/www.divvino.com.br\/blog\/wp-content\/uploads\/2023\/10\/champagne-cocktail-150x150.jpg\" class=\"attachment-150x150 size-150x150\" alt=\"Champagne cocktail\u00a0\" srcset=\"https:\/\/www.divvino.com.br\/blog\/wp-content\/uploads\/2023\/10\/champagne-cocktail-150x150.jpg 150w, https:\/\/www.divvino.com.br\/blog\/wp-content\/uploads\/2023\/10\/champagne-cocktail-300x300.jpg 300w, https:\/\/www.divvino.com.br\/blog\/wp-content\/uploads\/2023\/10\/champagne-cocktail.jpg 500w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/div>\n\t<div class=\"wprm-spacer\" style=\"height: 5px\"><\/div>\n\t\n\t<div class=\"wprm-spacer\" style=\"height: 2px\"><\/div>\n\t<a href=\"https:\/\/www.divvino.com.br\/blog\/wprm_print\/champagne-cocktail\" style=\"color: #333333;\" class=\"wprm-recipe-print wprm-recipe-link wprm-print-recipe-shortcode wprm-block-text-normal\" data-recipe-id=\"10050\" data-template=\"\" target=\"_blank\" rel=\"nofollow\"><span class=\"wprm-recipe-icon wprm-recipe-print-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"16px\" height=\"16px\" viewBox=\"0 0 24 24\"><g ><path fill=\"#333333\" d=\"M19,5.09V1c0-0.552-0.448-1-1-1H6C5.448,0,5,0.448,5,1v4.09C2.167,5.569,0,8.033,0,11v7c0,0.552,0.448,1,1,1h4v4c0,0.552,0.448,1,1,1h12c0.552,0,1-0.448,1-1v-4h4c0.552,0,1-0.448,1-1v-7C24,8.033,21.833,5.569,19,5.09z M7,2h10v3H7V2z M17,22H7v-9h10V22z M18,10c-0.552,0-1-0.448-1-1c0-0.552,0.448-1,1-1s1,0.448,1,1C19,9.552,18.552,10,18,10z\"\/><\/g><\/svg><\/span> Print<\/a>\n\t<a href=\"https:\/\/www.pinterest.com\/pin\/create\/bookmarklet\/?url=https%3A%2F%2Fwww.divvino.com.br%2Fblog%2Fdrinks-com-prosecco%2F&amp;media=https%3A%2F%2Fwww.divvino.com.br%2Fblog%2Fwp-content%2Fuploads%2F2023%2F10%2Fchampagne-cocktail.jpg&amp;description=Champagne+cocktail&amp;is_video=false\" style=\"color: #333333;\" class=\"wprm-recipe-pin wprm-recipe-link wprm-block-text-normal\" target=\"_blank\" rel=\"nofollow noopener\" data-recipe=\"10050\" data-url=\"https:\/\/www.divvino.com.br\/blog\/drinks-com-prosecco\/\" data-media=\"https:\/\/www.divvino.com.br\/blog\/wp-content\/uploads\/2023\/10\/champagne-cocktail.jpg\" data-description=\"Champagne cocktail\" data-repin=\"\"><span class=\"wprm-recipe-icon wprm-recipe-pin-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" viewBox=\"0 0 24 24\"><g class=\"nc-icon-wrapper\" fill=\"#333333\"><path fill=\"#333333\" d=\"M12,0C5.4,0,0,5.4,0,12c0,5.1,3.2,9.4,7.6,11.2c-0.1-0.9-0.2-2.4,0-3.4c0.2-0.9,1.4-6,1.4-6S8.7,13,8.7,12 c0-1.7,1-2.9,2.2-2.9c1,0,1.5,0.8,1.5,1.7c0,1-0.7,2.6-1,4c-0.3,1.2,0.6,2.2,1.8,2.2c2.1,0,3.8-2.2,3.8-5.5c0-2.9-2.1-4.9-5-4.9 c-3.4,0-5.4,2.6-5.4,5.2c0,1,0.4,2.1,0.9,2.7c0.1,0.1,0.1,0.2,0.1,0.3c-0.1,0.4-0.3,1.2-0.3,1.4c-0.1,0.2-0.2,0.3-0.4,0.2 c-1.5-0.7-2.4-2.9-2.4-4.6c0-3.8,2.8-7.3,7.9-7.3c4.2,0,7.4,3,7.4,6.9c0,4.1-2.6,7.5-6.2,7.5c-1.2,0-2.4-0.6-2.8-1.4 c0,0-0.6,2.3-0.7,2.9c-0.3,1-1,2.3-1.5,3.1C9.6,23.8,10.8,24,12,24c6.6,0,12-5.4,12-12C24,5.4,18.6,0,12,0z\"><\/path><\/g><\/svg><\/span> Pin<\/a>\n\t\n<\/div>\n<h2 class=\"wprm-recipe-name wprm-block-text-bold\"><span class=\"ez-toc-section\" id=\"Champagne_cocktail\"><\/span>Champagne cocktail<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<div class=\"wprm-spacer\" style=\"height: 5px\"><\/div>\n<div class=\"wprm-recipe-summary wprm-block-text-normal\">Um cl\u00e1ssico refrescante que real\u00e7a o sabor do espumante, o Champagne cocktail \u00e9 o drink ideal para celebra\u00e7\u00f5es. Veja sua prepara\u00e7\u00e3o!<\/div>\n<div class=\"wprm-spacer\"><\/div>\n\n<div class=\"wprm-spacer\"><\/div>\n\n<div class=\"wprm-spacer\"><\/div>\n\n\n\n\n\n<div class=\"wprm-recipe-ingredients-container wprm-recipe-10050-ingredients-container wprm-block-text-normal wprm-ingredient-style-regular wprm-recipe-images-before\" data-recipe=\"10050\" data-servings=\"0\"><h3 class=\"wprm-recipe-header wprm-recipe-ingredients-header wprm-block-text-bold wprm-align-left wprm-header-decoration-none\" style=\"\">Ingredients<\/h3><div class=\"wprm-recipe-ingredient-group\"><ul class=\"wprm-recipe-ingredients\"><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"0\"><span class=\"wprm-recipe-ingredient-amount\">120<\/span>&#32;<span class=\"wprm-recipe-ingredient-unit\">ml<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">de champanhe ou espumante<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"1\"><span class=\"wprm-recipe-ingredient-amount\">1<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">cubo de a\u00e7\u00facar<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"2\"><span class=\"wprm-recipe-ingredient-amount\">2<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">a 3 gotas de Angostura<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"3\"><span class=\"wprm-recipe-ingredient-amount\">60<\/span>&#32;<span class=\"wprm-recipe-ingredient-unit\">ml<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">de conhaque<\/span>&#32;<span class=\"wprm-recipe-ingredient-notes wprm-recipe-ingredient-notes-faded\">opcional, para um sabor mais robusto<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"4\"><span class=\"wprm-recipe-ingredient-amount\">1<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">cereja para decorar<\/span><\/li><\/ul><\/div><\/div>\n<div class=\"wprm-recipe-instructions-container wprm-recipe-10050-instructions-container wprm-block-text-normal\" data-recipe=\"10050\"><h3 class=\"wprm-recipe-header wprm-recipe-instructions-header wprm-block-text-bold wprm-align-left wprm-header-decoration-none\" style=\"\">Instructions<\/h3><div class=\"wprm-recipe-instruction-group\"><ul class=\"wprm-recipe-instructions\"><li id=\"wprm-recipe-10050-step-0-0\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\">Coloque um cubo de a\u00e7\u00facar no fundo de uma ta\u00e7a fl\u00fbte.<\/div><\/li><li id=\"wprm-recipe-10050-step-0-1\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\">Pingue de 2 a 3 gosta de Angostura sobre o cubo de a\u00e7\u00facar.<\/div><\/li><li id=\"wprm-recipe-10050-step-0-2\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\">Se desejar um drink mais complexo, adicione 60 ml de conhaque sobre o cubo de a\u00e7\u00facar embebido.<\/div><\/li><li id=\"wprm-recipe-10050-step-0-3\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\">Com cuidado, despeje o champanhe at\u00e9 preencher a ta\u00e7a. A efervesc\u00eancia ir\u00e1 misturar os sabores.<\/div><\/li><li id=\"wprm-recipe-10050-step-0-4\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\">Para finalizar, decore com uma cereja na borda ou dentro do copo.<\/div><\/li><\/ul><\/div><\/div>\n\n\n<\/div><\/div>\n<h2 aria-level=\"2\"><span class=\"ez-toc-section\" id=\"10_Pink_Elephant\"><\/span><b><span data-contrast=\"none\">10. Pink Elephant\u00a0<\/span><\/b><span data-ccp-props=\"{&quot;134245417&quot;:false,&quot;134245418&quot;:true,&quot;134245529&quot;:true}\">\u00a0<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span data-contrast=\"none\">O drink Pink Elephant possui diversas varia\u00e7\u00f5es, entre elas a adi\u00e7\u00e3o de espumante, proporcionando muita efervesc\u00eancia, leveza e refresc\u00e2ncia. O preparo \u00e9 simples e leva sabores maravilhosos, com as combina\u00e7\u00f5es de morango, hortel\u00e3 e vodka. Confira a receita do perfil <\/span><a href=\"https:\/\/www.tiktok.com\/@brindandoecomendo\" target=\"_blank\" rel=\"noopener\"><span data-contrast=\"none\">Brindando e Comendo<\/span><\/a><span data-contrast=\"none\">!<\/span><span data-ccp-props=\"{&quot;134245417&quot;:false}\">\u00a0<\/span><\/p>\n<div id=\"wprm-recipe-container-10052\" class=\"wprm-recipe-container\" data-recipe-id=\"10052\" data-servings=\"0\"><div class=\"wprm-recipe wprm-recipe-template-classic\"><div class=\"wprm-container-float-right\">\n\t\n\t<div class=\"wprm-spacer\" style=\"height: 5px\"><\/div>\n\t\n\t<div class=\"wprm-spacer\" style=\"height: 2px\"><\/div>\n\t<a href=\"https:\/\/www.divvino.com.br\/blog\/wprm_print\/pink-elephant\" style=\"color: #333333;\" class=\"wprm-recipe-print wprm-recipe-link wprm-print-recipe-shortcode wprm-block-text-normal\" data-recipe-id=\"10052\" data-template=\"\" target=\"_blank\" rel=\"nofollow\"><span class=\"wprm-recipe-icon wprm-recipe-print-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"16px\" height=\"16px\" viewBox=\"0 0 24 24\"><g ><path fill=\"#333333\" d=\"M19,5.09V1c0-0.552-0.448-1-1-1H6C5.448,0,5,0.448,5,1v4.09C2.167,5.569,0,8.033,0,11v7c0,0.552,0.448,1,1,1h4v4c0,0.552,0.448,1,1,1h12c0.552,0,1-0.448,1-1v-4h4c0.552,0,1-0.448,1-1v-7C24,8.033,21.833,5.569,19,5.09z M7,2h10v3H7V2z M17,22H7v-9h10V22z M18,10c-0.552,0-1-0.448-1-1c0-0.552,0.448-1,1-1s1,0.448,1,1C19,9.552,18.552,10,18,10z\"\/><\/g><\/svg><\/span> Print<\/a>\n\t\n\t\n<\/div>\n<h2 class=\"wprm-recipe-name wprm-block-text-bold\"><span class=\"ez-toc-section\" id=\"Pink_Elephant\"><\/span>Pink Elephant<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<div class=\"wprm-spacer\" style=\"height: 5px\"><\/div>\n<div class=\"wprm-recipe-summary wprm-block-text-normal\">Pink Elephant \u00e9 uma bebida com m\u00faltiplas vers\u00f5es, e uma das mais gostosas \u00e9 a que adiciona espumante. Veja como preparar para se refrescar!<\/div>\n<div class=\"wprm-spacer\"><\/div>\n\n<div class=\"wprm-spacer\"><\/div>\n\n<div class=\"wprm-spacer\"><\/div>\n\n\n\n\n\n<div class=\"wprm-recipe-ingredients-container wprm-recipe-10052-ingredients-container wprm-block-text-normal wprm-ingredient-style-regular wprm-recipe-images-before\" data-recipe=\"10052\" data-servings=\"0\"><h3 class=\"wprm-recipe-header wprm-recipe-ingredients-header wprm-block-text-bold wprm-align-left wprm-header-decoration-none\" style=\"\">Ingredients<\/h3><div class=\"wprm-recipe-ingredient-group\"><ul class=\"wprm-recipe-ingredients\"><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"0\"><span class=\"wprm-recipe-ingredient-amount\">4<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">morangos<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"1\"><span class=\"wprm-recipe-ingredient-name\">Folhas de hortel\u00e3<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"2\"><span class=\"wprm-recipe-ingredient-amount\">1<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">colher<\/span>&#32;<span class=\"wprm-recipe-ingredient-notes wprm-recipe-ingredient-notes-faded\">ch\u00e1 de a\u00e7\u00facar<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"3\"><span class=\"wprm-recipe-ingredient-amount\">25<\/span>&#32;<span class=\"wprm-recipe-ingredient-unit\">ml<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">de suco de lim\u00e3o<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"4\"><span class=\"wprm-recipe-ingredient-amount\">25<\/span>&#32;<span class=\"wprm-recipe-ingredient-unit\">ml<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">de vodka<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"5\"><span class=\"wprm-recipe-ingredient-name\">Espumante para completar<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"6\"><span class=\"wprm-recipe-ingredient-name\">Gelo a gosto<\/span><\/li><\/ul><\/div><\/div>\n<div class=\"wprm-recipe-instructions-container wprm-recipe-10052-instructions-container wprm-block-text-normal\" data-recipe=\"10052\"><h3 class=\"wprm-recipe-header wprm-recipe-instructions-header wprm-block-text-bold wprm-align-left wprm-header-decoration-none\" style=\"\">Instructions<\/h3><div class=\"wprm-recipe-instruction-group\"><ul class=\"wprm-recipe-instructions\"><li id=\"wprm-recipe-10052-step-0-0\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\">Em uma coqueteleira, comece macerando tr\u00eas morangos, folhas de hortel\u00e3 e a\u00e7\u00facar.<\/div><\/li><li id=\"wprm-recipe-10052-step-0-1\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\">Adicione gelo na coqueteleira e agite bem.<\/div><\/li><li id=\"wprm-recipe-10052-step-0-2\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\">Filtre e sirva em uma ta\u00e7a de martini.<\/div><\/li><li id=\"wprm-recipe-10052-step-0-3\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\">Complete com a vodka e o espumante.<\/div><\/li><li id=\"wprm-recipe-10052-step-0-4\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\">Decore com o outro morango na borda.<\/div><\/li><\/ul><\/div><\/div>\n<div id=\"wprm-recipe-video-container-10052\" class=\"wprm-recipe-video-container\"><h3 class=\"wprm-recipe-header wprm-recipe-video-header wprm-block-text-bold wprm-align-left wprm-header-decoration-none\" style=\"\">Video<\/h3><div class=\"wprm-recipe-video\"><a href=\"https:\/\/www.tiktok.com\/@brindandoecomendo\/video\/7197156922594757893?is_from_webapp=1&#038;sender_device=pc\">https:\/\/www.tiktok.com\/@brindandoecomendo\/video\/7197156922594757893?is_from_webapp=1&amp;sender_device=pc<\/a><\/div><\/div>\n\n<\/div><\/div>\n<blockquote class=\"tiktok-embed\" style=\"max-width: 605px; min-width: 325px;\" cite=\"https:\/\/www.tiktok.com\/@brindandoecomendo\/video\/7197156922594757893\" data-video-id=\"7197156922594757893\">\n<section><a title=\"@brindandoecomendo\" href=\"https:\/\/www.tiktok.com\/@brindandoecomendo?refer=embed\" target=\"_blank\" rel=\"noopener\">@brindandoecomendo<\/a> Bora aprender esse drink lindo e chiqu\u00e9rrimo: pink elephant! \ud83d\udc18\ud83d\udc95 3 morangos Folhas de hortel\u00e3 1 colher de a\u00e7\u00facar ou ado\u00e7ante 1\/2 dose (25ml) de lim\u00e3o 1\/2 dose (25ml) de vodka Espumante para completar (aproximadamente 100ml) Gelo Come\u00e7e macerando em uma coqueteleira os morangos, a hortel\u00e3 e o a\u00e7\u00facar. Adicione gelo e agite bem, depois filtre em uma ta\u00e7a de martini, adicione a vodka e finalize com o espumante, pronto! Dica: fica uma del\u00edcia com vodka de baunilha. Quem mais vai arrasar com esse drink? <a title=\"drinks\" href=\"https:\/\/www.tiktok.com\/tag\/drinks?refer=embed\" target=\"_blank\" rel=\"noopener\">#drinks<\/a> <a title=\"coquet\u00e9is\" href=\"https:\/\/www.tiktok.com\/tag\/coquet%C3%A9is?refer=embed\" target=\"_blank\" rel=\"noopener\">#coquet\u00e9is<\/a> <a title=\"viral\" href=\"https:\/\/www.tiktok.com\/tag\/viral?refer=embed\" target=\"_blank\" rel=\"noopener\">#viral<\/a> <a title=\"vodka\" href=\"https:\/\/www.tiktok.com\/tag\/vodka?refer=embed\" target=\"_blank\" rel=\"noopener\">#vodka<\/a> <a title=\"espumante\" href=\"https:\/\/www.tiktok.com\/tag\/espumante?refer=embed\" target=\"_blank\" rel=\"noopener\">#espumante<\/a> <a title=\"pinkelephant\" href=\"https:\/\/www.tiktok.com\/tag\/pinkelephant?refer=embed\" target=\"_blank\" rel=\"noopener\">#pinkelephant<\/a> <a title=\"drinkrosa\" href=\"https:\/\/www.tiktok.com\/tag\/drinkrosa?refer=embed\" target=\"_blank\" rel=\"noopener\">#drinkrosa<\/a> <a title=\"\u266c When I Ride - Ashley Mehta\" href=\"https:\/\/www.tiktok.com\/music\/When-I-Ride-7016196298517563393?refer=embed\" target=\"_blank\" rel=\"noopener\">\u266c When I Ride &#8211; Ashley Mehta<\/a><\/section>\n<\/blockquote>\n<p><script async src=\"https:\/\/www.tiktok.com\/embed.js\"><\/script><\/p>\n<p>&nbsp;<\/p>\n<h2 aria-level=\"2\"><span class=\"ez-toc-section\" id=\"11_Sangria_com_espumante\"><\/span><b><span data-contrast=\"none\">11. Sangria com espumante\u00a0<\/span><\/b><span data-ccp-props=\"{&quot;134245417&quot;:false,&quot;134245418&quot;:true,&quot;134245529&quot;:true}\">\u00a0<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span data-contrast=\"none\">A <\/span><a href=\"https:\/\/www.divvino.com.br\/blog\/receitas-de-sangria\/\" target=\"_blank\" rel=\"noopener\"><span data-contrast=\"none\">sangria<\/span><\/a><span data-contrast=\"none\"> \u00e9 uma bebida muito popular e refrescante, ideal para dias quentes, principalmente no ver\u00e3o. A caracter\u00edstica principal \u00e9 o uso de espumante, que pode ser um champanhe, um prosecco, um <\/span><a href=\"https:\/\/www.divvino.com.br\/blog\/espumante-cava\/\" target=\"_blank\" rel=\"noopener\"><span data-contrast=\"none\">cava<\/span><\/a><span data-contrast=\"none\"> ou outros tipos.\u00a0<\/span><span data-ccp-props=\"{&quot;134245417&quot;:false}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"none\">O sabor marcante vem da variedade de frutas frescas adicionadas. Confira como preparar a partir do v\u00eddeo do canal <\/span><a href=\"https:\/\/www.youtube.com\/c\/CasacomCheirodeCaf%C3%A9\" target=\"_blank\" rel=\"noopener\"><span data-contrast=\"none\">Casa com Cheiro de Caf\u00e9<\/span><\/a><span data-contrast=\"none\">!<\/span><span data-ccp-props=\"{&quot;134245417&quot;:false}\">\u00a0<\/span><\/p>\n<div id=\"wprm-recipe-container-10054\" class=\"wprm-recipe-container\" data-recipe-id=\"10054\" data-servings=\"0\"><div class=\"wprm-recipe wprm-recipe-template-classic\"><div class=\"wprm-container-float-right\">\n\t\n\t<div class=\"wprm-spacer\" style=\"height: 5px\"><\/div>\n\t\n\t<div class=\"wprm-spacer\" style=\"height: 2px\"><\/div>\n\t<a href=\"https:\/\/www.divvino.com.br\/blog\/wprm_print\/sangria-com-espumante\" style=\"color: #333333;\" class=\"wprm-recipe-print wprm-recipe-link wprm-print-recipe-shortcode wprm-block-text-normal\" data-recipe-id=\"10054\" data-template=\"\" target=\"_blank\" rel=\"nofollow\"><span class=\"wprm-recipe-icon wprm-recipe-print-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"16px\" height=\"16px\" viewBox=\"0 0 24 24\"><g ><path fill=\"#333333\" d=\"M19,5.09V1c0-0.552-0.448-1-1-1H6C5.448,0,5,0.448,5,1v4.09C2.167,5.569,0,8.033,0,11v7c0,0.552,0.448,1,1,1h4v4c0,0.552,0.448,1,1,1h12c0.552,0,1-0.448,1-1v-4h4c0.552,0,1-0.448,1-1v-7C24,8.033,21.833,5.569,19,5.09z M7,2h10v3H7V2z M17,22H7v-9h10V22z M18,10c-0.552,0-1-0.448-1-1c0-0.552,0.448-1,1-1s1,0.448,1,1C19,9.552,18.552,10,18,10z\"\/><\/g><\/svg><\/span> Print<\/a>\n\t\n\t\n<\/div>\n<h2 class=\"wprm-recipe-name wprm-block-text-bold\"><span class=\"ez-toc-section\" id=\"Sangria_com_espumante\"><\/span>Sangria com espumante<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<div class=\"wprm-spacer\" style=\"height: 5px\"><\/div>\n<div class=\"wprm-recipe-summary wprm-block-text-normal\">Um drink cl\u00e1ssico e muito refrescante \u00e9 a sangria com espumante. Aproveite o sabor das frutas e os toques da receita a seguir!<\/div>\n<div class=\"wprm-spacer\"><\/div>\n\n<div class=\"wprm-spacer\"><\/div>\n\n<div class=\"wprm-spacer\"><\/div>\n\n\n\n\n\n<div class=\"wprm-recipe-ingredients-container wprm-recipe-10054-ingredients-container wprm-block-text-normal wprm-ingredient-style-regular wprm-recipe-images-before\" data-recipe=\"10054\" data-servings=\"0\"><h3 class=\"wprm-recipe-header wprm-recipe-ingredients-header wprm-block-text-bold wprm-align-left wprm-header-decoration-none\" style=\"\">Ingredients<\/h3><div class=\"wprm-recipe-ingredient-group\"><ul class=\"wprm-recipe-ingredients\"><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"0\"><span class=\"wprm-recipe-ingredient-amount\">5<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">morangos levemente amassados<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"1\"><span class=\"wprm-recipe-ingredient-amount\">1<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">ma\u00e7\u00e3 em cubos<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"2\"><span class=\"wprm-recipe-ingredient-amount\">10<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">uvas verdes sem sementes cortadas ao meio<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"3\"><span class=\"wprm-recipe-ingredient-amount\">1<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">lim\u00e3o-siciliano em rodelas<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"4\"><span class=\"wprm-recipe-ingredient-amount\">1<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">lata de Sprite<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"5\"><span class=\"wprm-recipe-ingredient-amount\">1<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">garrafa de espumante<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"6\"><span class=\"wprm-recipe-ingredient-amount\">50<\/span>&#32;<span class=\"wprm-recipe-ingredient-unit\">ml<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">de vodka<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"7\"><span class=\"wprm-recipe-ingredient-name\">Hortel\u00e3 a gosto<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"8\"><span class=\"wprm-recipe-ingredient-amount\">1<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">canela em pau<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"9\"><span class=\"wprm-recipe-ingredient-name\">Gelo a gosto<\/span><\/li><\/ul><\/div><\/div>\n<div class=\"wprm-recipe-instructions-container wprm-recipe-10054-instructions-container wprm-block-text-normal\" data-recipe=\"10054\"><h3 class=\"wprm-recipe-header wprm-recipe-instructions-header wprm-block-text-bold wprm-align-left wprm-header-decoration-none\" style=\"\">Instructions<\/h3><div class=\"wprm-recipe-instruction-group\"><ul class=\"wprm-recipe-instructions\"><li id=\"wprm-recipe-10054-step-0-0\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\">Em uma jarra, adicione os morangos, a ma\u00e7\u00e3, as uvas e o lim\u00e3o-siciliano.<\/div><\/li><li id=\"wprm-recipe-10054-step-0-1\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\">Inclua o gelo, a vodka e o refrigerante.<\/div><\/li><li id=\"wprm-recipe-10054-step-0-2\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\">Complemente com o espumante at\u00e9 completar.<\/div><\/li><li id=\"wprm-recipe-10054-step-0-3\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\">Finalize com folhas de hortel\u00e3 e uma canela em pau. Misture e sirva.<\/div><\/li><\/ul><\/div><\/div>\n<div id=\"wprm-recipe-video-container-10054\" class=\"wprm-recipe-video-container\"><h3 class=\"wprm-recipe-header wprm-recipe-video-header wprm-block-text-bold wprm-align-left wprm-header-decoration-none\" style=\"\">Video<\/h3><div class=\"wprm-recipe-video\"><a href=\"https:\/\/youtu.be\/lmgKDL4UrhE\">https:\/\/youtu.be\/lmgKDL4UrhE<\/a><\/div><\/div>\n\n<\/div><\/div>\n<p><iframe loading=\"lazy\" title=\"SANGRIA DE ESPUMANTE #shorts\" src=\"https:\/\/www.youtube.com\/embed\/lmgKDL4UrhE\" width=\"866\" height=\"487\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<h2 aria-level=\"2\"><span class=\"ez-toc-section\" id=\"12_Clericot_tradicional\"><\/span><b><span data-contrast=\"none\">12. Clericot tradicional\u00a0<\/span><\/b><span data-ccp-props=\"{&quot;134245417&quot;:false,&quot;134245418&quot;:true,&quot;134245529&quot;:true}\">\u00a0<\/span><span data-ccp-props=\"{&quot;134245417&quot;:false}\">\u00a0<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span data-contrast=\"none\">O clericot \u00e9 um <\/span><span data-contrast=\"none\">drink com frutas e espumante<\/span><span data-contrast=\"none\"> refrescante e muito popular na Am\u00e9rica Latina. \u00c9 frequentemente consumido durante o ver\u00e3o, em festas ou reuni\u00f5es sociais.<\/span><span data-ccp-props=\"{&quot;134245417&quot;:false}\">\u00a0<\/span><span data-ccp-props=\"{&quot;134245417&quot;:false}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"none\">A bebida tem algumas semelhan\u00e7as com a sangria espanhola, devido \u00e0s frutas, mas se difere por utilizar vinhos brancos ou espumante na receita original, tornando mais leve e refrescante. Confira a receita!<\/span><span data-ccp-props=\"{&quot;134245417&quot;:false}\">\u00a0<\/span><\/p>\n<div id=\"wprm-recipe-container-10056\" class=\"wprm-recipe-container\" data-recipe-id=\"10056\" data-servings=\"0\"><div class=\"wprm-recipe wprm-recipe-template-classic\"><div class=\"wprm-container-float-right\">\n\t<div class=\"wprm-recipe-image wprm-block-image-normal\"><img loading=\"lazy\" decoding=\"async\" style=\"border-width: 0px;border-style: solid;border-color: #666666;\" width=\"150\" height=\"150\" src=\"https:\/\/www.divvino.com.br\/blog\/wp-content\/uploads\/2023\/10\/clericot-tradicional-150x150.jpg\" class=\"attachment-150x150 size-150x150\" alt=\"Clericot tradicional\u00a0\u00a0\" srcset=\"https:\/\/www.divvino.com.br\/blog\/wp-content\/uploads\/2023\/10\/clericot-tradicional-150x150.jpg 150w, https:\/\/www.divvino.com.br\/blog\/wp-content\/uploads\/2023\/10\/clericot-tradicional-300x300.jpg 300w, https:\/\/www.divvino.com.br\/blog\/wp-content\/uploads\/2023\/10\/clericot-tradicional.jpg 500w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/div>\n\t<div class=\"wprm-spacer\" style=\"height: 5px\"><\/div>\n\t\n\t<div class=\"wprm-spacer\" style=\"height: 2px\"><\/div>\n\t<a href=\"https:\/\/www.divvino.com.br\/blog\/wprm_print\/clericot-tradicional\" style=\"color: #333333;\" class=\"wprm-recipe-print wprm-recipe-link wprm-print-recipe-shortcode wprm-block-text-normal\" data-recipe-id=\"10056\" data-template=\"\" target=\"_blank\" rel=\"nofollow\"><span class=\"wprm-recipe-icon wprm-recipe-print-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"16px\" height=\"16px\" viewBox=\"0 0 24 24\"><g ><path fill=\"#333333\" d=\"M19,5.09V1c0-0.552-0.448-1-1-1H6C5.448,0,5,0.448,5,1v4.09C2.167,5.569,0,8.033,0,11v7c0,0.552,0.448,1,1,1h4v4c0,0.552,0.448,1,1,1h12c0.552,0,1-0.448,1-1v-4h4c0.552,0,1-0.448,1-1v-7C24,8.033,21.833,5.569,19,5.09z M7,2h10v3H7V2z M17,22H7v-9h10V22z M18,10c-0.552,0-1-0.448-1-1c0-0.552,0.448-1,1-1s1,0.448,1,1C19,9.552,18.552,10,18,10z\"\/><\/g><\/svg><\/span> Print<\/a>\n\t<a href=\"https:\/\/www.pinterest.com\/pin\/create\/bookmarklet\/?url=https%3A%2F%2Fwww.divvino.com.br%2Fblog%2Fdrinks-com-prosecco%2F&amp;media=https%3A%2F%2Fwww.divvino.com.br%2Fblog%2Fwp-content%2Fuploads%2F2023%2F10%2Fclericot-tradicional.jpg&amp;description=Clericot+tradicional&amp;is_video=false\" style=\"color: #333333;\" class=\"wprm-recipe-pin wprm-recipe-link wprm-block-text-normal\" target=\"_blank\" rel=\"nofollow noopener\" data-recipe=\"10056\" data-url=\"https:\/\/www.divvino.com.br\/blog\/drinks-com-prosecco\/\" data-media=\"https:\/\/www.divvino.com.br\/blog\/wp-content\/uploads\/2023\/10\/clericot-tradicional.jpg\" data-description=\"Clericot tradicional\" data-repin=\"\"><span class=\"wprm-recipe-icon wprm-recipe-pin-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" viewBox=\"0 0 24 24\"><g class=\"nc-icon-wrapper\" fill=\"#333333\"><path fill=\"#333333\" d=\"M12,0C5.4,0,0,5.4,0,12c0,5.1,3.2,9.4,7.6,11.2c-0.1-0.9-0.2-2.4,0-3.4c0.2-0.9,1.4-6,1.4-6S8.7,13,8.7,12 c0-1.7,1-2.9,2.2-2.9c1,0,1.5,0.8,1.5,1.7c0,1-0.7,2.6-1,4c-0.3,1.2,0.6,2.2,1.8,2.2c2.1,0,3.8-2.2,3.8-5.5c0-2.9-2.1-4.9-5-4.9 c-3.4,0-5.4,2.6-5.4,5.2c0,1,0.4,2.1,0.9,2.7c0.1,0.1,0.1,0.2,0.1,0.3c-0.1,0.4-0.3,1.2-0.3,1.4c-0.1,0.2-0.2,0.3-0.4,0.2 c-1.5-0.7-2.4-2.9-2.4-4.6c0-3.8,2.8-7.3,7.9-7.3c4.2,0,7.4,3,7.4,6.9c0,4.1-2.6,7.5-6.2,7.5c-1.2,0-2.4-0.6-2.8-1.4 c0,0-0.6,2.3-0.7,2.9c-0.3,1-1,2.3-1.5,3.1C9.6,23.8,10.8,24,12,24c6.6,0,12-5.4,12-12C24,5.4,18.6,0,12,0z\"><\/path><\/g><\/svg><\/span> Pin<\/a>\n\t\n<\/div>\n<h2 class=\"wprm-recipe-name wprm-block-text-bold\"><span class=\"ez-toc-section\" id=\"Clericot_tradicional\"><\/span>Clericot tradicional<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<div class=\"wprm-spacer\" style=\"height: 5px\"><\/div>\n<div class=\"wprm-recipe-summary wprm-block-text-normal\">O Clericot \u00e9 uma bebida sul-americana similar \u00e0 sangria, mas muito mais refrescante pelo uso do espumante ou de vinho branco. Veja o passo a passo!<\/div>\n<div class=\"wprm-spacer\"><\/div>\n\n<div class=\"wprm-spacer\"><\/div>\n\n<div class=\"wprm-spacer\"><\/div>\n\n\n\n\n\n<div class=\"wprm-recipe-ingredients-container wprm-recipe-10056-ingredients-container wprm-block-text-normal wprm-ingredient-style-regular wprm-recipe-images-before\" data-recipe=\"10056\" data-servings=\"0\"><h3 class=\"wprm-recipe-header wprm-recipe-ingredients-header wprm-block-text-bold wprm-align-left wprm-header-decoration-none\" style=\"\">Ingredients<\/h3><div class=\"wprm-recipe-ingredient-group\"><ul class=\"wprm-recipe-ingredients\"><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"0\"><span class=\"wprm-recipe-ingredient-amount\">2<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">x\u00edcaras<\/span>&#32;<span class=\"wprm-recipe-ingredient-notes wprm-recipe-ingredient-notes-faded\">ch\u00e1 de frutas picadas da sua prefer\u00eancia<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"1\"><span class=\"wprm-recipe-ingredient-amount\">1<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">dose de licor de laranja<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"2\"><span class=\"wprm-recipe-ingredient-amount\">1<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">garrafa de espumante<\/span>&#32;<span class=\"wprm-recipe-ingredient-notes wprm-recipe-ingredient-notes-faded\">ou vinho branco<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"3\"><span class=\"wprm-recipe-ingredient-name\">Gelo a gosto<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"4\"><span class=\"wprm-recipe-ingredient-name\">A\u00e7\u00facar a gosto<\/span><\/li><\/ul><\/div><\/div>\n<div class=\"wprm-recipe-instructions-container wprm-recipe-10056-instructions-container wprm-block-text-normal\" data-recipe=\"10056\"><h3 class=\"wprm-recipe-header wprm-recipe-instructions-header wprm-block-text-bold wprm-align-left wprm-header-decoration-none\" style=\"\">Instructions<\/h3><div class=\"wprm-recipe-instruction-group\"><ul class=\"wprm-recipe-instructions\"><li id=\"wprm-recipe-10056-step-0-0\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\">Em uma jarra, adicione as frutas picadas e o licor de laranja.<\/div><\/li><li id=\"wprm-recipe-10056-step-0-1\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\">Na sequ\u00eancia, complete com o espumante de sua prefer\u00eancia e gelo.<\/div><\/li><li id=\"wprm-recipe-10056-step-0-2\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\">Coloque a\u00e7\u00facar a gosto e sirva.<\/div><\/li><\/ul><\/div><\/div>\n\n\n<\/div><\/div>\n<h2 aria-level=\"2\"><span class=\"ez-toc-section\" id=\"13_Hibisco_Spritz\"><\/span><b><span data-contrast=\"none\">13. Hibisco Spritz\u00a0<\/span><\/b><span data-ccp-props=\"{&quot;134245417&quot;:false,&quot;134245418&quot;:true,&quot;134245529&quot;:true}\">\u00a0<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span data-contrast=\"none\">O Hibisco Spritz \u00e9 uma bebida refrescante e sofisticada, perfeita para dias quentes ou ocasi\u00f5es especiais. A acidez do hibisco, a do\u00e7ura do a\u00e7\u00facar e as borbulhas do espumante criam uma experi\u00eancia \u00fanica e prazerosa no paladar.<\/span><span data-ccp-props=\"{&quot;134245417&quot;:false}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"none\">O drink apresenta uma cor maravilhosa vermelha ou rubi vibrante, por conta das flores de hibisco, deixando o coquetel atraente. Elas tamb\u00e9m contribuem para o aroma floral e ligeiramente c\u00edtrico. O espumante ainda adiciona um leve toque de fermenta\u00e7\u00e3o natural, devido \u00e0 efervesc\u00eancia. Confira a receita!<\/span><span data-ccp-props=\"{&quot;134245417&quot;:false}\">\u00a0<\/span><\/p>\n<div id=\"wprm-recipe-container-10058\" class=\"wprm-recipe-container\" data-recipe-id=\"10058\" data-servings=\"0\"><div class=\"wprm-recipe wprm-recipe-template-classic\"><div class=\"wprm-container-float-right\">\n\t<div class=\"wprm-recipe-image wprm-block-image-normal\"><img loading=\"lazy\" decoding=\"async\" style=\"border-width: 0px;border-style: solid;border-color: #666666;\" width=\"150\" height=\"150\" src=\"https:\/\/www.divvino.com.br\/blog\/wp-content\/uploads\/2023\/10\/hibisco-spritz-150x150.jpg\" class=\"attachment-150x150 size-150x150\" alt=\"Hibisco Spritz\u00a0\u00a0\" srcset=\"https:\/\/www.divvino.com.br\/blog\/wp-content\/uploads\/2023\/10\/hibisco-spritz-150x150.jpg 150w, https:\/\/www.divvino.com.br\/blog\/wp-content\/uploads\/2023\/10\/hibisco-spritz-300x300.jpg 300w, https:\/\/www.divvino.com.br\/blog\/wp-content\/uploads\/2023\/10\/hibisco-spritz.jpg 500w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/div>\n\t<div class=\"wprm-spacer\" style=\"height: 5px\"><\/div>\n\t\n\t<div class=\"wprm-spacer\" style=\"height: 2px\"><\/div>\n\t<a href=\"https:\/\/www.divvino.com.br\/blog\/wprm_print\/hibisco-spritz\" style=\"color: #333333;\" class=\"wprm-recipe-print wprm-recipe-link wprm-print-recipe-shortcode wprm-block-text-normal\" data-recipe-id=\"10058\" data-template=\"\" target=\"_blank\" rel=\"nofollow\"><span class=\"wprm-recipe-icon wprm-recipe-print-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"16px\" height=\"16px\" viewBox=\"0 0 24 24\"><g ><path fill=\"#333333\" d=\"M19,5.09V1c0-0.552-0.448-1-1-1H6C5.448,0,5,0.448,5,1v4.09C2.167,5.569,0,8.033,0,11v7c0,0.552,0.448,1,1,1h4v4c0,0.552,0.448,1,1,1h12c0.552,0,1-0.448,1-1v-4h4c0.552,0,1-0.448,1-1v-7C24,8.033,21.833,5.569,19,5.09z M7,2h10v3H7V2z M17,22H7v-9h10V22z M18,10c-0.552,0-1-0.448-1-1c0-0.552,0.448-1,1-1s1,0.448,1,1C19,9.552,18.552,10,18,10z\"\/><\/g><\/svg><\/span> Print<\/a>\n\t<a href=\"https:\/\/www.pinterest.com\/pin\/create\/bookmarklet\/?url=https%3A%2F%2Fwww.divvino.com.br%2Fblog%2Fdrinks-com-prosecco%2F&amp;media=https%3A%2F%2Fwww.divvino.com.br%2Fblog%2Fwp-content%2Fuploads%2F2023%2F10%2Fhibisco-spritz.jpg&amp;description=Hibisco+Spritz&amp;is_video=false\" style=\"color: #333333;\" class=\"wprm-recipe-pin wprm-recipe-link wprm-block-text-normal\" target=\"_blank\" rel=\"nofollow noopener\" data-recipe=\"10058\" data-url=\"https:\/\/www.divvino.com.br\/blog\/drinks-com-prosecco\/\" data-media=\"https:\/\/www.divvino.com.br\/blog\/wp-content\/uploads\/2023\/10\/hibisco-spritz.jpg\" data-description=\"Hibisco Spritz\" data-repin=\"\"><span class=\"wprm-recipe-icon wprm-recipe-pin-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" viewBox=\"0 0 24 24\"><g class=\"nc-icon-wrapper\" fill=\"#333333\"><path fill=\"#333333\" d=\"M12,0C5.4,0,0,5.4,0,12c0,5.1,3.2,9.4,7.6,11.2c-0.1-0.9-0.2-2.4,0-3.4c0.2-0.9,1.4-6,1.4-6S8.7,13,8.7,12 c0-1.7,1-2.9,2.2-2.9c1,0,1.5,0.8,1.5,1.7c0,1-0.7,2.6-1,4c-0.3,1.2,0.6,2.2,1.8,2.2c2.1,0,3.8-2.2,3.8-5.5c0-2.9-2.1-4.9-5-4.9 c-3.4,0-5.4,2.6-5.4,5.2c0,1,0.4,2.1,0.9,2.7c0.1,0.1,0.1,0.2,0.1,0.3c-0.1,0.4-0.3,1.2-0.3,1.4c-0.1,0.2-0.2,0.3-0.4,0.2 c-1.5-0.7-2.4-2.9-2.4-4.6c0-3.8,2.8-7.3,7.9-7.3c4.2,0,7.4,3,7.4,6.9c0,4.1-2.6,7.5-6.2,7.5c-1.2,0-2.4-0.6-2.8-1.4 c0,0-0.6,2.3-0.7,2.9c-0.3,1-1,2.3-1.5,3.1C9.6,23.8,10.8,24,12,24c6.6,0,12-5.4,12-12C24,5.4,18.6,0,12,0z\"><\/path><\/g><\/svg><\/span> Pin<\/a>\n\t\n<\/div>\n<h2 class=\"wprm-recipe-name wprm-block-text-bold\"><span class=\"ez-toc-section\" id=\"Hibisco_Spritz\"><\/span>Hibisco Spritz<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<div class=\"wprm-spacer\" style=\"height: 5px\"><\/div>\n<div class=\"wprm-recipe-summary wprm-block-text-normal\">O Hibisco Spritz \u00e9 a receita certa para se refrescar com um drink sofisticado, leve e muito arom\u00e1tico por conta das flores. Siga o preparo!<\/div>\n<div class=\"wprm-spacer\"><\/div>\n\n<div class=\"wprm-spacer\"><\/div>\n\n<div class=\"wprm-spacer\"><\/div>\n\n\n\n\n\n<div class=\"wprm-recipe-ingredients-container wprm-recipe-10058-ingredients-container wprm-block-text-normal wprm-ingredient-style-regular wprm-recipe-images-before\" data-recipe=\"10058\" data-servings=\"0\"><h3 class=\"wprm-recipe-header wprm-recipe-ingredients-header wprm-block-text-bold wprm-align-left wprm-header-decoration-none\" style=\"\">Ingredients<\/h3><div class=\"wprm-recipe-ingredient-group\"><ul class=\"wprm-recipe-ingredients\"><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"0\"><span class=\"wprm-recipe-ingredient-amount\">1<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">x\u00edcara<\/span>&#32;<span class=\"wprm-recipe-ingredient-notes wprm-recipe-ingredient-notes-faded\">ch\u00e1 de flores de hibisco secas<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"1\"><span class=\"wprm-recipe-ingredient-amount\">4<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">x\u00edcaras<\/span>&#32;<span class=\"wprm-recipe-ingredient-notes wprm-recipe-ingredient-notes-faded\">ch\u00e1 de \u00e1gua<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"2\"><span class=\"wprm-recipe-ingredient-amount\">1\/4<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">x\u00edcara<\/span>&#32;<span class=\"wprm-recipe-ingredient-notes wprm-recipe-ingredient-notes-faded\">ch\u00e1 de a\u00e7\u00facar<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"3\"><span class=\"wprm-recipe-ingredient-amount\">1<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">garrafa de espumante seco<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"4\"><span class=\"wprm-recipe-ingredient-name\">\u00c1gua com g\u00e1s<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"5\"><span class=\"wprm-recipe-ingredient-name\">Fatias de lim\u00e3o ou laranja para decorar<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"6\"><span class=\"wprm-recipe-ingredient-name\">Gelo a gosto<\/span><\/li><\/ul><\/div><\/div>\n<div class=\"wprm-recipe-instructions-container wprm-recipe-10058-instructions-container wprm-block-text-normal\" data-recipe=\"10058\"><h3 class=\"wprm-recipe-header wprm-recipe-instructions-header wprm-block-text-bold wprm-align-left wprm-header-decoration-none\" style=\"\">Instructions<\/h3><div class=\"wprm-recipe-instruction-group\"><ul class=\"wprm-recipe-instructions\"><li id=\"wprm-recipe-10058-step-0-0\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\">Em uma panela, ferva a \u00e1gua e adicione as flores de hibisco secas.<\/div><\/li><li id=\"wprm-recipe-10058-step-0-1\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\">Desligue o fogo e deixe as flores em infus\u00e3o por 10 minutos.<\/div><\/li><li id=\"wprm-recipe-10058-step-0-2\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\">Coe e adicione o a\u00e7\u00facar ao ch\u00e1 ainda quente, mexendo at\u00e9 dissolver completamente.<\/div><\/li><li id=\"wprm-recipe-10058-step-0-3\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\">Deixe o ch\u00e1 esfriar completamente antes de fazer o drink.<\/div><\/li><li id=\"wprm-recipe-10058-step-0-4\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\">Em um copo alto, adicione gelo.<\/div><\/li><li id=\"wprm-recipe-10058-step-0-5\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\">Acrescente aproximadamente 1\/4 de x\u00edcara do ch\u00e1 de hibisco frio.<\/div><\/li><li id=\"wprm-recipe-10058-step-0-6\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\">Complete o copo com metade de espumante e metade de \u00e1gua com g\u00e1s.<\/div><\/li><li id=\"wprm-recipe-10058-step-0-7\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\">Misture suavemente.<\/div><\/li><li id=\"wprm-recipe-10058-step-0-8\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\">Decore com uma fatia de lim\u00e3o ou laranja.<\/div><\/li><\/ul><\/div><\/div>\n\n\n<\/div><\/div>\n<h2 aria-level=\"2\"><span class=\"ez-toc-section\" id=\"14_Batidinha_de_espumante_rose\"><\/span><b><span data-contrast=\"none\">14. Batidinha de espumante ros\u00e9<\/span><\/b><span data-ccp-props=\"{&quot;134245417&quot;:false,&quot;134245418&quot;:true,&quot;134245529&quot;:true}\">\u00a0<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span data-contrast=\"none\">Quem n\u00e3o gosta de se refrescar e tomar uma <\/span><span data-contrast=\"none\">batida com champanhe<\/span><span data-contrast=\"none\"> junto com as entradas. Essa receita traz toda a cremosidade, com o sabor incr\u00edvel e frutado do ros\u00e9. Assista ao preparo do canal <\/span><a href=\"https:\/\/www.youtube.com\/@Drinkeiros\"><span data-contrast=\"none\">Drinkeiros<\/span><\/a><span data-contrast=\"auto\">!<\/span><span data-ccp-props=\"{&quot;134245417&quot;:false}\">\u00a0<\/span><\/p>\n<div id=\"wprm-recipe-container-10060\" class=\"wprm-recipe-container\" data-recipe-id=\"10060\" data-servings=\"0\"><div class=\"wprm-recipe wprm-recipe-template-classic\"><div class=\"wprm-container-float-right\">\n\t\n\t<div class=\"wprm-spacer\" style=\"height: 5px\"><\/div>\n\t\n\t<div class=\"wprm-spacer\" style=\"height: 2px\"><\/div>\n\t<a href=\"https:\/\/www.divvino.com.br\/blog\/wprm_print\/batidinha-de-espumante-rose\" style=\"color: #333333;\" class=\"wprm-recipe-print wprm-recipe-link wprm-print-recipe-shortcode wprm-block-text-normal\" data-recipe-id=\"10060\" data-template=\"\" target=\"_blank\" rel=\"nofollow\"><span class=\"wprm-recipe-icon wprm-recipe-print-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"16px\" height=\"16px\" viewBox=\"0 0 24 24\"><g ><path fill=\"#333333\" d=\"M19,5.09V1c0-0.552-0.448-1-1-1H6C5.448,0,5,0.448,5,1v4.09C2.167,5.569,0,8.033,0,11v7c0,0.552,0.448,1,1,1h4v4c0,0.552,0.448,1,1,1h12c0.552,0,1-0.448,1-1v-4h4c0.552,0,1-0.448,1-1v-7C24,8.033,21.833,5.569,19,5.09z M7,2h10v3H7V2z M17,22H7v-9h10V22z M18,10c-0.552,0-1-0.448-1-1c0-0.552,0.448-1,1-1s1,0.448,1,1C19,9.552,18.552,10,18,10z\"\/><\/g><\/svg><\/span> Print<\/a>\n\t\n\t\n<\/div>\n<h2 class=\"wprm-recipe-name wprm-block-text-bold\"><span class=\"ez-toc-section\" id=\"Batidinha_de_espumante_rose\"><\/span>Batidinha de espumante ros\u00e9<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<div class=\"wprm-spacer\" style=\"height: 5px\"><\/div>\n<div class=\"wprm-recipe-summary wprm-block-text-normal\">A batidinha de espumante ros\u00e9 \u00e9 muito cremosa e saborosa. Vai ser um sucesso junto com os aperitivos. Confira a receita!<\/div>\n<div class=\"wprm-spacer\"><\/div>\n\n<div class=\"wprm-spacer\"><\/div>\n\n<div class=\"wprm-spacer\"><\/div>\n\n\n\n\n\n<div class=\"wprm-recipe-ingredients-container wprm-recipe-10060-ingredients-container wprm-block-text-normal wprm-ingredient-style-regular wprm-recipe-images-before\" data-recipe=\"10060\" data-servings=\"0\"><h3 class=\"wprm-recipe-header wprm-recipe-ingredients-header wprm-block-text-bold wprm-align-left wprm-header-decoration-none\" style=\"\">Ingredients<\/h3><div class=\"wprm-recipe-ingredient-group\"><ul class=\"wprm-recipe-ingredients\"><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"0\"><span class=\"wprm-recipe-ingredient-amount\">1<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">copo de gelo picado<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"1\"><span class=\"wprm-recipe-ingredient-amount\">100<\/span>&#32;<span class=\"wprm-recipe-ingredient-unit\">ml<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">de leite condensado<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"2\"><span class=\"wprm-recipe-ingredient-amount\">50<\/span>&#32;<span class=\"wprm-recipe-ingredient-unit\">ml<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">de coco ralado<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"3\"><span class=\"wprm-recipe-ingredient-amount\">25<\/span>&#32;<span class=\"wprm-recipe-ingredient-unit\">ml<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">de Malibu<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"4\"><span class=\"wprm-recipe-ingredient-amount\">300<\/span>&#32;<span class=\"wprm-recipe-ingredient-unit\">ml<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">de espumante ros\u00e9<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"5\"><span class=\"wprm-recipe-ingredient-name\">Gelo a gosto<\/span><\/li><\/ul><\/div><\/div>\n<div class=\"wprm-recipe-instructions-container wprm-recipe-10060-instructions-container wprm-block-text-normal\" data-recipe=\"10060\"><h3 class=\"wprm-recipe-header wprm-recipe-instructions-header wprm-block-text-bold wprm-align-left wprm-header-decoration-none\" style=\"\">Instructions<\/h3><div class=\"wprm-recipe-instruction-group\"><ul class=\"wprm-recipe-instructions\"><li id=\"wprm-recipe-10060-step-0-0\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\">Adicione todos os ingredientes no liquidificador e bata.<\/div><\/li><li id=\"wprm-recipe-10060-step-0-1\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\">Sirva em um copo alto.<\/div><\/li><li id=\"wprm-recipe-10060-step-0-2\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\">Finalize com gelo triturado e coco ralado.<\/div><\/li><\/ul><\/div><\/div>\n<div id=\"wprm-recipe-video-container-10060\" class=\"wprm-recipe-video-container\"><h3 class=\"wprm-recipe-header wprm-recipe-video-header wprm-block-text-bold wprm-align-left wprm-header-decoration-none\" style=\"\">Video<\/h3><div class=\"wprm-recipe-video\"><a href=\"https:\/\/youtu.be\/uByVm84bYfU\">https:\/\/youtu.be\/uByVm84bYfU<\/a><\/div><\/div>\n<div class=\"wprm-recipe-notes-container wprm-block-text-normal\"><h3 class=\"wprm-recipe-header wprm-recipe-notes-header wprm-block-text-bold wprm-align-left wprm-header-decoration-none\" style=\"\">Notes<\/h3><div class=\"wprm-recipe-notes\"><span style=\"display: block;\">Dica: complemente o drink acompanhado de um picol\u00e9 de morango para harmonizar os sabores. <\/span><\/div><\/div>\n<\/div><\/div>\n<p><iframe loading=\"lazy\" title=\"Batida de espumante Ros\u00e9\" src=\"https:\/\/www.youtube.com\/embed\/uByVm84bYfU\" width=\"866\" height=\"487\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<h2 aria-level=\"2\"><span class=\"ez-toc-section\" id=\"15_Sparkling_Sunrise\"><\/span><b><span data-contrast=\"none\">15. Sparkling Sunrise\u00a0<\/span><\/b><span data-ccp-props=\"{&quot;134245417&quot;:false,&quot;134245418&quot;:true,&quot;134245529&quot;:true}\">\u00a0<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span data-contrast=\"none\">O Sparkling Sunrise \u00e9 uma bebida visualmente impressionante e absolutamente deliciosa. \u00c9 perfeita para brunches, reuni\u00f5es ao p\u00f4r do sol ou qualquer celebra\u00e7\u00e3o em que um <\/span><span data-contrast=\"none\">drink com espumante brut<\/span><span data-contrast=\"none\"> e frutado possa ser apreciado.<\/span><span data-ccp-props=\"{&quot;134245417&quot;:false}\">\u00a0<\/span><\/p>\n<div id=\"wprm-recipe-container-10062\" class=\"wprm-recipe-container\" data-recipe-id=\"10062\" data-servings=\"0\"><div class=\"wprm-recipe wprm-recipe-template-classic\"><div class=\"wprm-container-float-right\">\n\t<div class=\"wprm-recipe-image wprm-block-image-normal\"><img loading=\"lazy\" decoding=\"async\" style=\"border-width: 0px;border-style: solid;border-color: #666666;\" width=\"150\" height=\"150\" src=\"https:\/\/www.divvino.com.br\/blog\/wp-content\/uploads\/2023\/10\/sparkling-sunrise-150x150.jpg\" class=\"attachment-150x150 size-150x150\" alt=\"Sparkling Sunrise\" srcset=\"https:\/\/www.divvino.com.br\/blog\/wp-content\/uploads\/2023\/10\/sparkling-sunrise-150x150.jpg 150w, https:\/\/www.divvino.com.br\/blog\/wp-content\/uploads\/2023\/10\/sparkling-sunrise-300x300.jpg 300w, https:\/\/www.divvino.com.br\/blog\/wp-content\/uploads\/2023\/10\/sparkling-sunrise.jpg 500w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/div>\n\t<div class=\"wprm-spacer\" style=\"height: 5px\"><\/div>\n\t\n\t<div class=\"wprm-spacer\" style=\"height: 2px\"><\/div>\n\t<a href=\"https:\/\/www.divvino.com.br\/blog\/wprm_print\/sparkling-sunrise\" style=\"color: #333333;\" class=\"wprm-recipe-print wprm-recipe-link wprm-print-recipe-shortcode wprm-block-text-normal\" data-recipe-id=\"10062\" data-template=\"\" target=\"_blank\" rel=\"nofollow\"><span class=\"wprm-recipe-icon wprm-recipe-print-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"16px\" height=\"16px\" viewBox=\"0 0 24 24\"><g ><path fill=\"#333333\" d=\"M19,5.09V1c0-0.552-0.448-1-1-1H6C5.448,0,5,0.448,5,1v4.09C2.167,5.569,0,8.033,0,11v7c0,0.552,0.448,1,1,1h4v4c0,0.552,0.448,1,1,1h12c0.552,0,1-0.448,1-1v-4h4c0.552,0,1-0.448,1-1v-7C24,8.033,21.833,5.569,19,5.09z M7,2h10v3H7V2z M17,22H7v-9h10V22z M18,10c-0.552,0-1-0.448-1-1c0-0.552,0.448-1,1-1s1,0.448,1,1C19,9.552,18.552,10,18,10z\"\/><\/g><\/svg><\/span> Print<\/a>\n\t<a href=\"https:\/\/www.pinterest.com\/pin\/create\/bookmarklet\/?url=https%3A%2F%2Fwww.divvino.com.br%2Fblog%2Fdrinks-com-prosecco%2F&amp;media=https%3A%2F%2Fwww.divvino.com.br%2Fblog%2Fwp-content%2Fuploads%2F2023%2F10%2Fsparkling-sunrise.jpg&amp;description=Sparkling+Sunrise&amp;is_video=false\" style=\"color: #333333;\" class=\"wprm-recipe-pin wprm-recipe-link wprm-block-text-normal\" target=\"_blank\" rel=\"nofollow noopener\" data-recipe=\"10062\" data-url=\"https:\/\/www.divvino.com.br\/blog\/drinks-com-prosecco\/\" data-media=\"https:\/\/www.divvino.com.br\/blog\/wp-content\/uploads\/2023\/10\/sparkling-sunrise.jpg\" data-description=\"Sparkling Sunrise\" data-repin=\"\"><span class=\"wprm-recipe-icon wprm-recipe-pin-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" viewBox=\"0 0 24 24\"><g class=\"nc-icon-wrapper\" fill=\"#333333\"><path fill=\"#333333\" d=\"M12,0C5.4,0,0,5.4,0,12c0,5.1,3.2,9.4,7.6,11.2c-0.1-0.9-0.2-2.4,0-3.4c0.2-0.9,1.4-6,1.4-6S8.7,13,8.7,12 c0-1.7,1-2.9,2.2-2.9c1,0,1.5,0.8,1.5,1.7c0,1-0.7,2.6-1,4c-0.3,1.2,0.6,2.2,1.8,2.2c2.1,0,3.8-2.2,3.8-5.5c0-2.9-2.1-4.9-5-4.9 c-3.4,0-5.4,2.6-5.4,5.2c0,1,0.4,2.1,0.9,2.7c0.1,0.1,0.1,0.2,0.1,0.3c-0.1,0.4-0.3,1.2-0.3,1.4c-0.1,0.2-0.2,0.3-0.4,0.2 c-1.5-0.7-2.4-2.9-2.4-4.6c0-3.8,2.8-7.3,7.9-7.3c4.2,0,7.4,3,7.4,6.9c0,4.1-2.6,7.5-6.2,7.5c-1.2,0-2.4-0.6-2.8-1.4 c0,0-0.6,2.3-0.7,2.9c-0.3,1-1,2.3-1.5,3.1C9.6,23.8,10.8,24,12,24c6.6,0,12-5.4,12-12C24,5.4,18.6,0,12,0z\"><\/path><\/g><\/svg><\/span> Pin<\/a>\n\t\n<\/div>\n<h2 class=\"wprm-recipe-name wprm-block-text-bold\"><span class=\"ez-toc-section\" id=\"Sparkling_Sunrise\"><\/span>Sparkling Sunrise<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<div class=\"wprm-spacer\" style=\"height: 5px\"><\/div>\n<div class=\"wprm-recipe-summary wprm-block-text-normal\">Sparkling Sunrise \u00e9 um drink bel\u00edssimo e muito gostoso, ideal para brunches ou eventos no p\u00f4r do sol. Confira a receita!<\/div>\n<div class=\"wprm-spacer\"><\/div>\n\n<div class=\"wprm-spacer\"><\/div>\n\n<div class=\"wprm-spacer\"><\/div>\n\n\n\n\n\n<div class=\"wprm-recipe-ingredients-container wprm-recipe-10062-ingredients-container wprm-block-text-normal wprm-ingredient-style-regular wprm-recipe-images-before\" data-recipe=\"10062\" data-servings=\"0\"><h3 class=\"wprm-recipe-header wprm-recipe-ingredients-header wprm-block-text-bold wprm-align-left wprm-header-decoration-none\" style=\"\">Ingredients<\/h3><div class=\"wprm-recipe-ingredient-group\"><ul class=\"wprm-recipe-ingredients\"><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"0\"><span class=\"wprm-recipe-ingredient-amount\">1\/2<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">x\u00edcara<\/span>&#32;<span class=\"wprm-recipe-ingredient-notes wprm-recipe-ingredient-notes-faded\">ch\u00e1 de suco de laranja<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"1\"><span class=\"wprm-recipe-ingredient-amount\">1\/4<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">x\u00edcara<\/span>&#32;<span class=\"wprm-recipe-ingredient-notes wprm-recipe-ingredient-notes-faded\">ch\u00e1 de suco de grenadine (xarope de rom\u00e3)<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"2\"><span class=\"wprm-recipe-ingredient-amount\">1<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">garrafa de espumante brut<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"3\"><span class=\"wprm-recipe-ingredient-name\">Gelo<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"4\"><span class=\"wprm-recipe-ingredient-name\">Rodelas de laranja para decorar<\/span><\/li><\/ul><\/div><\/div>\n<div class=\"wprm-recipe-instructions-container wprm-recipe-10062-instructions-container wprm-block-text-normal\" data-recipe=\"10062\"><h3 class=\"wprm-recipe-header wprm-recipe-instructions-header wprm-block-text-bold wprm-align-left wprm-header-decoration-none\" style=\"\">Instructions<\/h3><div class=\"wprm-recipe-instruction-group\"><ul class=\"wprm-recipe-instructions\"><li id=\"wprm-recipe-10062-step-0-0\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\">Antes de come\u00e7ar a montar o drink, certifique-se de que as bebidas estejam todas frias.<\/div><\/li><li id=\"wprm-recipe-10062-step-0-1\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\">Em um copo alto ou ta\u00e7a fl\u00fbte, adicione gelo.<\/div><\/li><li id=\"wprm-recipe-10062-step-0-2\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\">Despeje o suco de laranja.<\/div><\/li><li id=\"wprm-recipe-10062-step-0-3\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\">Com cuidado, adicione o espumante at\u00e9 quase o final.<\/div><\/li><li id=\"wprm-recipe-10062-step-0-4\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\">Depois, coloque o suco de grenadine devagar. Como \u00e9 mais denso, deve afundar lentamente at\u00e9 ao fundo do copo, dando um efeito de \"nascer do sol\" (sunrise) com gradiente de cores.<\/div><\/li><li id=\"wprm-recipe-10062-step-0-5\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\">Decore com uma rodela de laranja na borda do copo.<\/div><\/li><\/ul><\/div><\/div>\n\n\n<\/div><\/div>\n<h3 aria-level=\"2\"><b><span data-contrast=\"none\">16. Poinsettia\u00a0<\/span><\/b><span data-ccp-props=\"{&quot;134245417&quot;:false,&quot;134245418&quot;:true,&quot;134245529&quot;:true}\">\u00a0<\/span><\/h3>\n<p><span data-contrast=\"none\">O Poinsettia \u00e9 um coquetel elegante, f\u00e1cil de preparar e perfeito para festas. Sua combina\u00e7\u00e3o de sabores \u00e9 ao mesmo tempo refrescante e sofisticada, o que o torna uma excelente escolha para brindar em comemora\u00e7\u00f5es e eventos especiais.<\/span><span data-ccp-props=\"{&quot;134245417&quot;:false}\">\u00a0<\/span><span data-ccp-props=\"{&quot;134245417&quot;:false}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"none\">O drink \u00e9 conhecido por sua linda cor vermelha, apresenta aromas frutados pelo cranberry e toques c\u00edtricos do licor de laranja. O espumante \u00e9 respons\u00e1vel pela efervesc\u00eancia e leveza, al\u00e9m do toque seco que harmoniza com os sabores adocicados.<\/span><span data-ccp-props=\"{&quot;134245417&quot;:false}\">\u00a0<\/span><\/p>\n<div id=\"wprm-recipe-container-10064\" class=\"wprm-recipe-container\" data-recipe-id=\"10064\" data-servings=\"0\"><div class=\"wprm-recipe wprm-recipe-template-classic\"><div class=\"wprm-container-float-right\">\n\t<div class=\"wprm-recipe-image wprm-block-image-normal\"><img loading=\"lazy\" decoding=\"async\" style=\"border-width: 0px;border-style: solid;border-color: #666666;\" width=\"150\" height=\"150\" src=\"https:\/\/www.divvino.com.br\/blog\/wp-content\/uploads\/2023\/10\/poinsettia-150x150.jpg\" class=\"attachment-150x150 size-150x150\" alt=\"Poinsettia\u00a0\" srcset=\"https:\/\/www.divvino.com.br\/blog\/wp-content\/uploads\/2023\/10\/poinsettia-150x150.jpg 150w, https:\/\/www.divvino.com.br\/blog\/wp-content\/uploads\/2023\/10\/poinsettia-300x300.jpg 300w, https:\/\/www.divvino.com.br\/blog\/wp-content\/uploads\/2023\/10\/poinsettia.jpg 500w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/div>\n\t<div class=\"wprm-spacer\" style=\"height: 5px\"><\/div>\n\t\n\t<div class=\"wprm-spacer\" style=\"height: 2px\"><\/div>\n\t<a href=\"https:\/\/www.divvino.com.br\/blog\/wprm_print\/poinsettia\" style=\"color: #333333;\" class=\"wprm-recipe-print wprm-recipe-link wprm-print-recipe-shortcode wprm-block-text-normal\" data-recipe-id=\"10064\" data-template=\"\" target=\"_blank\" rel=\"nofollow\"><span class=\"wprm-recipe-icon wprm-recipe-print-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"16px\" height=\"16px\" viewBox=\"0 0 24 24\"><g ><path fill=\"#333333\" d=\"M19,5.09V1c0-0.552-0.448-1-1-1H6C5.448,0,5,0.448,5,1v4.09C2.167,5.569,0,8.033,0,11v7c0,0.552,0.448,1,1,1h4v4c0,0.552,0.448,1,1,1h12c0.552,0,1-0.448,1-1v-4h4c0.552,0,1-0.448,1-1v-7C24,8.033,21.833,5.569,19,5.09z M7,2h10v3H7V2z M17,22H7v-9h10V22z M18,10c-0.552,0-1-0.448-1-1c0-0.552,0.448-1,1-1s1,0.448,1,1C19,9.552,18.552,10,18,10z\"\/><\/g><\/svg><\/span> Print<\/a>\n\t<a href=\"https:\/\/www.pinterest.com\/pin\/create\/bookmarklet\/?url=https%3A%2F%2Fwww.divvino.com.br%2Fblog%2Fdrinks-com-prosecco%2F&amp;media=https%3A%2F%2Fwww.divvino.com.br%2Fblog%2Fwp-content%2Fuploads%2F2023%2F10%2Fpoinsettia.jpg&amp;description=Poinsettia&amp;is_video=false\" style=\"color: #333333;\" class=\"wprm-recipe-pin wprm-recipe-link wprm-block-text-normal\" target=\"_blank\" rel=\"nofollow noopener\" data-recipe=\"10064\" data-url=\"https:\/\/www.divvino.com.br\/blog\/drinks-com-prosecco\/\" data-media=\"https:\/\/www.divvino.com.br\/blog\/wp-content\/uploads\/2023\/10\/poinsettia.jpg\" data-description=\"Poinsettia\" data-repin=\"\"><span class=\"wprm-recipe-icon wprm-recipe-pin-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" viewBox=\"0 0 24 24\"><g class=\"nc-icon-wrapper\" fill=\"#333333\"><path fill=\"#333333\" d=\"M12,0C5.4,0,0,5.4,0,12c0,5.1,3.2,9.4,7.6,11.2c-0.1-0.9-0.2-2.4,0-3.4c0.2-0.9,1.4-6,1.4-6S8.7,13,8.7,12 c0-1.7,1-2.9,2.2-2.9c1,0,1.5,0.8,1.5,1.7c0,1-0.7,2.6-1,4c-0.3,1.2,0.6,2.2,1.8,2.2c2.1,0,3.8-2.2,3.8-5.5c0-2.9-2.1-4.9-5-4.9 c-3.4,0-5.4,2.6-5.4,5.2c0,1,0.4,2.1,0.9,2.7c0.1,0.1,0.1,0.2,0.1,0.3c-0.1,0.4-0.3,1.2-0.3,1.4c-0.1,0.2-0.2,0.3-0.4,0.2 c-1.5-0.7-2.4-2.9-2.4-4.6c0-3.8,2.8-7.3,7.9-7.3c4.2,0,7.4,3,7.4,6.9c0,4.1-2.6,7.5-6.2,7.5c-1.2,0-2.4-0.6-2.8-1.4 c0,0-0.6,2.3-0.7,2.9c-0.3,1-1,2.3-1.5,3.1C9.6,23.8,10.8,24,12,24c6.6,0,12-5.4,12-12C24,5.4,18.6,0,12,0z\"><\/path><\/g><\/svg><\/span> Pin<\/a>\n\t\n<\/div>\n<h2 class=\"wprm-recipe-name wprm-block-text-bold\"><span class=\"ez-toc-section\" id=\"Poinsettia\"><\/span>Poinsettia<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<div class=\"wprm-spacer\" style=\"height: 5px\"><\/div>\n<div class=\"wprm-recipe-summary wprm-block-text-normal\">Poinsettia \u00e9 um drink elegante, com sabores equilibrados e perfeitos para uma comemora\u00e7\u00e3o. Prepare seu brinde e veja a receita!<\/div>\n<div class=\"wprm-spacer\"><\/div>\n\n<div class=\"wprm-spacer\"><\/div>\n\n<div class=\"wprm-spacer\"><\/div>\n\n\n\n\n\n<div class=\"wprm-recipe-ingredients-container wprm-recipe-10064-ingredients-container wprm-block-text-normal wprm-ingredient-style-regular wprm-recipe-images-before\" data-recipe=\"10064\" data-servings=\"0\"><h3 class=\"wprm-recipe-header wprm-recipe-ingredients-header wprm-block-text-bold wprm-align-left wprm-header-decoration-none\" style=\"\">Ingredients<\/h3><div class=\"wprm-recipe-ingredient-group\"><ul class=\"wprm-recipe-ingredients\"><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"0\"><span class=\"wprm-recipe-ingredient-amount\">1\/2<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">x\u00edcara<\/span>&#32;<span class=\"wprm-recipe-ingredient-notes wprm-recipe-ingredient-notes-faded\">ch\u00e1 de suco de cranberry<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"1\"><span class=\"wprm-recipe-ingredient-amount\">2<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">colheres<\/span>&#32;<span class=\"wprm-recipe-ingredient-notes wprm-recipe-ingredient-notes-faded\">sopa de licor de laranja<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"2\"><span class=\"wprm-recipe-ingredient-name\">Champagne ou outro espumante brut<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"3\"><span class=\"wprm-recipe-ingredient-name\">Ramos de alecrim para decorar<\/span>&#32;<span class=\"wprm-recipe-ingredient-notes wprm-recipe-ingredient-notes-faded\">opcional<\/span><\/li><\/ul><\/div><\/div>\n<div class=\"wprm-recipe-instructions-container wprm-recipe-10064-instructions-container wprm-block-text-normal\" data-recipe=\"10064\"><h3 class=\"wprm-recipe-header wprm-recipe-instructions-header wprm-block-text-bold wprm-align-left wprm-header-decoration-none\" style=\"\">Instructions<\/h3><div class=\"wprm-recipe-instruction-group\"><ul class=\"wprm-recipe-instructions\"><li id=\"wprm-recipe-10064-step-0-0\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\">Em uma ta\u00e7a fl\u00fbte, adicione o suco de cranberry.<\/div><\/li><li id=\"wprm-recipe-10064-step-0-1\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\">Em seguida, coloque o licor de laranja.<\/div><\/li><li id=\"wprm-recipe-10064-step-0-2\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\">Complete o restante com o espumante seco.<\/div><\/li><li id=\"wprm-recipe-10064-step-0-3\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\">Misture delicadamente para combinar os sabores.<\/div><\/li><li id=\"wprm-recipe-10064-step-0-4\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\" style=\"margin-bottom: 5px;\">Se quiser, decore com um ramo de alecrim e sirva.<\/div><\/li><\/ul><\/div><\/div>\n\n\n<\/div><\/div>\n<p><span class=\"TextRun SCXW57255208 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW57255208 BCX0\">Gostou de conhecer nossas sugest\u00f5es de<\/span><\/span><span class=\"TextRun SCXW57255208 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"none\"> <span class=\"NormalTextRun SCXW57255208 BCX0\">drinks<\/span><span class=\"NormalTextRun SCXW57255208 BCX0\"> com espumante<\/span><\/span><span class=\"TextRun SCXW57255208 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW57255208 BCX0\">? No <\/span><\/span><a class=\"Hyperlink SCXW57255208 BCX0\" href=\"https:\/\/www.divvino.com.br\/?utm_source=blog&amp;utm_medium=post&amp;utm_content=divvino&amp;utm_campaign=drinks-com-prosecco\" target=\"_blank\" rel=\"noreferrer noopener\"><span class=\"TextRun Underlined SCXW57255208 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW57255208 BCX0\" data-ccp-charstyle=\"Hyperlink\">divvino.com.br<\/span><\/span><\/a><span class=\"TextRun SCXW57255208 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW57255208 BCX0\">, voc\u00ea encontra <\/span><\/span><span class=\"TextRun SCXW57255208 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW57255208 BCX0\">diversas <\/span><\/span><span class=\"TextRun SCXW57255208 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW57255208 BCX0\">op\u00e7\u00f5es <\/span><span class=\"NormalTextRun SCXW57255208 BCX0\">que podem ser utilizadas para degustar ou preparar seus drinks favoritos. Clique no banner abaixo e acesse o e-commerce para conhec\u00ea-l<\/span><span class=\"NormalTextRun SCXW57255208 BCX0\">a<\/span><span class=\"NormalTextRun SCXW57255208 BCX0\">s!<\/span><\/span><span class=\"EOP SCXW57255208 BCX0\" data-ccp-props=\"{&quot;134245417&quot;:false}\">\u00a0<\/span><\/p>\n<p><a href=\"https:\/\/www.divvino.com.br\/vinhos\/espumante\/?utm_source=blog&amp;utm_medium=post&amp;utm_content=espumantes-no-divvino&amp;utm_campaign=drinks-com-espumante\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-7270 size-full\" src=\"https:\/\/www.divvino.com.br\/blog\/wp-content\/uploads\/2023\/08\/cta-espumantes-no-divvino.png\" alt=\"cta espumantes divvino\" width=\"810\" height=\"300\" srcset=\"https:\/\/www.divvino.com.br\/blog\/wp-content\/uploads\/2023\/08\/cta-espumantes-no-divvino.png 810w, https:\/\/www.divvino.com.br\/blog\/wp-content\/uploads\/2023\/08\/cta-espumantes-no-divvino-300x111.png 300w, https:\/\/www.divvino.com.br\/blog\/wp-content\/uploads\/2023\/08\/cta-espumantes-no-divvino-768x284.png 768w\" sizes=\"(max-width: 810px) 100vw, 810px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se os dias quentes pedem por refresco, nada melhor do que celebrar esses momentos acompanhado de drinks com espumante. Leves e elegantes, a bebida proporciona sofistica\u00e7\u00e3o para roubar a cena em festas, celebra\u00e7\u00f5es, eventos ao ar livre ou para relaxar&hellip;<\/p>\n","protected":false},"author":2,"featured_media":7509,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"wprm-recipe-roundup-name":"","wprm-recipe-roundup-description":"","footnotes":""},"categories":[15],"tags":[],"post_series":[],"class_list":["post-7505","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dicas-e-curiosidades","entry","has-media"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>16 drinks com espumante para se deliciar nos dias quentes<\/title>\n<meta name=\"description\" content=\"Fazer drinks com espumantes \u00e9 a aposta certa para quem deseja se refrescar. Aproveite as celebra\u00e7\u00f5es e veja receitas para fazer!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.divvino.com.br\/blog\/drinks-com-prosecco\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"16 drinks com espumante para se deliciar nos dias quentes\" \/>\n<meta property=\"og:description\" content=\"Fazer drinks com espumantes \u00e9 a aposta certa para quem deseja se refrescar. Aproveite as celebra\u00e7\u00f5es e veja receitas para fazer!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.divvino.com.br\/blog\/drinks-com-prosecco\/\" \/>\n<meta property=\"og:site_name\" content=\"Divvino - Conhe\u00e7a tudo sobre o mundo dos vinhos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/pt-br.facebook.com\/divvinovinhos\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-12T10:00:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-22T18:10:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.divvino.com.br\/blog\/wp-content\/uploads\/2023\/09\/drinks-com-prosecco-imagem-destacada.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"divvino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@divvino_vinhos\" \/>\n<meta name=\"twitter:site\" content=\"@divvino_vinhos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"divvino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.divvino.com.br\/blog\/drinks-com-prosecco\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.divvino.com.br\/blog\/drinks-com-prosecco\/\"},\"author\":{\"name\":\"divvino\",\"@id\":\"https:\/\/www.divvino.com.br\/blog\/#\/schema\/person\/b24915a61e7f52407242aa23b626cf58\"},\"headline\":\"16 drinks com espumante para se deliciar nos dias quentes\",\"datePublished\":\"2024-12-12T10:00:29+00:00\",\"dateModified\":\"2025-01-22T18:10:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.divvino.com.br\/blog\/drinks-com-prosecco\/\"},\"wordCount\":2662,\"publisher\":{\"@id\":\"https:\/\/www.divvino.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.divvino.com.br\/blog\/drinks-com-prosecco\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.divvino.com.br\/blog\/wp-content\/uploads\/2023\/09\/drinks-com-prosecco-imagem-destacada.jpg\",\"articleSection\":[\"Dicas e curiosidades\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.divvino.com.br\/blog\/drinks-com-prosecco\/\",\"url\":\"https:\/\/www.divvino.com.br\/blog\/drinks-com-prosecco\/\",\"name\":\"16 drinks com espumante para se deliciar nos dias quentes\",\"isPartOf\":{\"@id\":\"https:\/\/www.divvino.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.divvino.com.br\/blog\/drinks-com-prosecco\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.divvino.com.br\/blog\/drinks-com-prosecco\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.divvino.com.br\/blog\/wp-content\/uploads\/2023\/09\/drinks-com-prosecco-imagem-destacada.jpg\",\"datePublished\":\"2024-12-12T10:00:29+00:00\",\"dateModified\":\"2025-01-22T18:10:55+00:00\",\"description\":\"Fazer drinks com espumantes \u00e9 a aposta certa para quem deseja se refrescar. Aproveite as celebra\u00e7\u00f5es e veja receitas para fazer!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.divvino.com.br\/blog\/drinks-com-prosecco\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.divvino.com.br\/blog\/drinks-com-prosecco\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.divvino.com.br\/blog\/drinks-com-prosecco\/#primaryimage\",\"url\":\"https:\/\/www.divvino.com.br\/blog\/wp-content\/uploads\/2023\/09\/drinks-com-prosecco-imagem-destacada.jpg\",\"contentUrl\":\"https:\/\/www.divvino.com.br\/blog\/wp-content\/uploads\/2023\/09\/drinks-com-prosecco-imagem-destacada.jpg\",\"width\":1000,\"height\":667,\"caption\":\"tr\u00eas drinks com Prosecco\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.divvino.com.br\/blog\/drinks-com-prosecco\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.divvino.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"16 drinks com espumante para se deliciar nos dias quentes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.divvino.com.br\/blog\/#website\",\"url\":\"https:\/\/www.divvino.com.br\/blog\/\",\"name\":\"Divvino | Saiba tudo sobre o mundo dos vinhos\",\"description\":\"Conhe\u00e7a tudo sobre o mundo dos vinhos\",\"publisher\":{\"@id\":\"https:\/\/www.divvino.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.divvino.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.divvino.com.br\/blog\/#organization\",\"name\":\"Divvino\",\"url\":\"https:\/\/www.divvino.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.divvino.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.divvino.com.br\/blog\/wp-content\/uploads\/2019\/12\/divvino-blog-logo-branca2.png\",\"contentUrl\":\"https:\/\/www.divvino.com.br\/blog\/wp-content\/uploads\/2019\/12\/divvino-blog-logo-branca2.png\",\"width\":352,\"height\":110,\"caption\":\"Divvino\"},\"image\":{\"@id\":\"https:\/\/www.divvino.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/pt-br.facebook.com\/divvinovinhos\/\",\"https:\/\/x.com\/divvino_vinhos\",\"https:\/\/www.instagram.com\/divvino_oficial\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.divvino.com.br\/blog\/#\/schema\/person\/b24915a61e7f52407242aa23b626cf58\",\"name\":\"divvino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.divvino.com.br\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ff2056824247072588c53a23aa083722?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ff2056824247072588c53a23aa083722?s=96&d=mm&r=g\",\"caption\":\"divvino\"},\"url\":\"https:\/\/www.divvino.com.br\/blog\/author\/nacao-digital\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"16 drinks com espumante para se deliciar nos dias quentes","description":"Fazer drinks com espumantes \u00e9 a aposta certa para quem deseja se refrescar. Aproveite as celebra\u00e7\u00f5es e veja receitas para fazer!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.divvino.com.br\/blog\/drinks-com-prosecco\/","og_locale":"pt_BR","og_type":"article","og_title":"16 drinks com espumante para se deliciar nos dias quentes","og_description":"Fazer drinks com espumantes \u00e9 a aposta certa para quem deseja se refrescar. Aproveite as celebra\u00e7\u00f5es e veja receitas para fazer!","og_url":"https:\/\/www.divvino.com.br\/blog\/drinks-com-prosecco\/","og_site_name":"Divvino - Conhe\u00e7a tudo sobre o mundo dos vinhos","article_publisher":"https:\/\/pt-br.facebook.com\/divvinovinhos\/","article_published_time":"2024-12-12T10:00:29+00:00","article_modified_time":"2025-01-22T18:10:55+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/www.divvino.com.br\/blog\/wp-content\/uploads\/2023\/09\/drinks-com-prosecco-imagem-destacada.jpg","type":"image\/jpeg"}],"author":"divvino","twitter_card":"summary_large_image","twitter_creator":"@divvino_vinhos","twitter_site":"@divvino_vinhos","twitter_misc":{"Escrito por":"divvino","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.divvino.com.br\/blog\/drinks-com-prosecco\/#article","isPartOf":{"@id":"https:\/\/www.divvino.com.br\/blog\/drinks-com-prosecco\/"},"author":{"name":"divvino","@id":"https:\/\/www.divvino.com.br\/blog\/#\/schema\/person\/b24915a61e7f52407242aa23b626cf58"},"headline":"16 drinks com espumante para se deliciar nos dias quentes","datePublished":"2024-12-12T10:00:29+00:00","dateModified":"2025-01-22T18:10:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.divvino.com.br\/blog\/drinks-com-prosecco\/"},"wordCount":2662,"publisher":{"@id":"https:\/\/www.divvino.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.divvino.com.br\/blog\/drinks-com-prosecco\/#primaryimage"},"thumbnailUrl":"https:\/\/www.divvino.com.br\/blog\/wp-content\/uploads\/2023\/09\/drinks-com-prosecco-imagem-destacada.jpg","articleSection":["Dicas e curiosidades"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.divvino.com.br\/blog\/drinks-com-prosecco\/","url":"https:\/\/www.divvino.com.br\/blog\/drinks-com-prosecco\/","name":"16 drinks com espumante para se deliciar nos dias quentes","isPartOf":{"@id":"https:\/\/www.divvino.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.divvino.com.br\/blog\/drinks-com-prosecco\/#primaryimage"},"image":{"@id":"https:\/\/www.divvino.com.br\/blog\/drinks-com-prosecco\/#primaryimage"},"thumbnailUrl":"https:\/\/www.divvino.com.br\/blog\/wp-content\/uploads\/2023\/09\/drinks-com-prosecco-imagem-destacada.jpg","datePublished":"2024-12-12T10:00:29+00:00","dateModified":"2025-01-22T18:10:55+00:00","description":"Fazer drinks com espumantes \u00e9 a aposta certa para quem deseja se refrescar. Aproveite as celebra\u00e7\u00f5es e veja receitas para fazer!","breadcrumb":{"@id":"https:\/\/www.divvino.com.br\/blog\/drinks-com-prosecco\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.divvino.com.br\/blog\/drinks-com-prosecco\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.divvino.com.br\/blog\/drinks-com-prosecco\/#primaryimage","url":"https:\/\/www.divvino.com.br\/blog\/wp-content\/uploads\/2023\/09\/drinks-com-prosecco-imagem-destacada.jpg","contentUrl":"https:\/\/www.divvino.com.br\/blog\/wp-content\/uploads\/2023\/09\/drinks-com-prosecco-imagem-destacada.jpg","width":1000,"height":667,"caption":"tr\u00eas drinks com Prosecco"},{"@type":"BreadcrumbList","@id":"https:\/\/www.divvino.com.br\/blog\/drinks-com-prosecco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.divvino.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"16 drinks com espumante para se deliciar nos dias quentes"}]},{"@type":"WebSite","@id":"https:\/\/www.divvino.com.br\/blog\/#website","url":"https:\/\/www.divvino.com.br\/blog\/","name":"Divvino | Saiba tudo sobre o mundo dos vinhos","description":"Conhe\u00e7a tudo sobre o mundo dos vinhos","publisher":{"@id":"https:\/\/www.divvino.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.divvino.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.divvino.com.br\/blog\/#organization","name":"Divvino","url":"https:\/\/www.divvino.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.divvino.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.divvino.com.br\/blog\/wp-content\/uploads\/2019\/12\/divvino-blog-logo-branca2.png","contentUrl":"https:\/\/www.divvino.com.br\/blog\/wp-content\/uploads\/2019\/12\/divvino-blog-logo-branca2.png","width":352,"height":110,"caption":"Divvino"},"image":{"@id":"https:\/\/www.divvino.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/pt-br.facebook.com\/divvinovinhos\/","https:\/\/x.com\/divvino_vinhos","https:\/\/www.instagram.com\/divvino_oficial\/"]},{"@type":"Person","@id":"https:\/\/www.divvino.com.br\/blog\/#\/schema\/person\/b24915a61e7f52407242aa23b626cf58","name":"divvino","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.divvino.com.br\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/ff2056824247072588c53a23aa083722?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ff2056824247072588c53a23aa083722?s=96&d=mm&r=g","caption":"divvino"},"url":"https:\/\/www.divvino.com.br\/blog\/author\/nacao-digital\/"}]}},"_links":{"self":[{"href":"https:\/\/www.divvino.com.br\/blog\/wp-json\/wp\/v2\/posts\/7505"}],"collection":[{"href":"https:\/\/www.divvino.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.divvino.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.divvino.com.br\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.divvino.com.br\/blog\/wp-json\/wp\/v2\/comments?post=7505"}],"version-history":[{"count":8,"href":"https:\/\/www.divvino.com.br\/blog\/wp-json\/wp\/v2\/posts\/7505\/revisions"}],"predecessor-version":[{"id":10089,"href":"https:\/\/www.divvino.com.br\/blog\/wp-json\/wp\/v2\/posts\/7505\/revisions\/10089"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.divvino.com.br\/blog\/wp-json\/wp\/v2\/media\/7509"}],"wp:attachment":[{"href":"https:\/\/www.divvino.com.br\/blog\/wp-json\/wp\/v2\/media?parent=7505"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.divvino.com.br\/blog\/wp-json\/wp\/v2\/categories?post=7505"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.divvino.com.br\/blog\/wp-json\/wp\/v2\/tags?post=7505"},{"taxonomy":"post_series","embeddable":true,"href":"https:\/\/www.divvino.com.br\/blog\/wp-json\/wp\/v2\/post_series?post=7505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}